{"id":29409,"date":"2020-10-27T14:00:31","date_gmt":"2020-10-27T11:00:31","guid":{"rendered":"https:\/\/avicennaint.com\/?page_id=29409"},"modified":"2023-07-26T18:21:52","modified_gmt":"2023-07-26T15:21:52","slug":"transplant-de-par","status":"publish","type":"page","link":"https:\/\/avicennaint.com\/ro\/transplant-de-par\/","title":{"rendered":"Centrul De Transplant De P\u0103r Al Spitalului Avicenna"},"content":{"rendered":"<div id=\"cmsmasters_row_v26wn0lu4\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_fullwidth\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner cmsmasters_row_fullwidth\">\n<div class=\"cmsmasters_row_margin\">\n<div id=\"cmsmasters_column_p7j122su6\" class=\"cmsmasters_column two_third\">\n<div class=\"cmsmasters_column_inner\"><div id=\"cmsmasters_heading_swvjaj1z1k\" class=\"cmsmasters_heading_wrap cmsmasters_heading_align_center\">\n\t<h1 class=\"cmsmasters_heading\">Centrul De Transplant De P\u0103r Al Spitalului Avicenna<\/h1>\n<\/div><div id=\"cmsmasters_heading_5omzvr6c1l\" class=\"cmsmasters_heading_wrap cmsmasters_heading_align_center\">\n\t<h3 class=\"cmsmasters_heading\">Aspect natural<\/h3>\n<\/div><div id=\"cmsmasters_heading_ix1megn6pc\" class=\"cmsmasters_heading_wrap cmsmasters_heading_align_center\">\n\t<h3 class=\"cmsmasters_heading\">P\u0103r S\u0103n\u0103tos<\/h3>\n<\/div><div id=\"cmsmasters_heading_615d03eqs8\" class=\"cmsmasters_heading_wrap cmsmasters_heading_align_center\">\n\t<h3 class=\"cmsmasters_heading\">Ob\u021bine\u021bi cre\u015ftere a p\u0103rului pe tot parcursul vie\u021bii<\/h3>\n<\/div><div id=\"cmsmasters_heading_a21bd3nm3a\" class=\"cmsmasters_heading_wrap cmsmasters_heading_align_center\">\n\t<h3 class=\"cmsmasters_heading\">datorit\u0103 tehnicilor avansate de transplant de p\u0103r \u0219i a personalui expert \u00een domeniu.<\/h3>\n<\/div><div id=\"cmsmasters_button_rv0hx3g4lc\" class=\"button_wrap\"><a href=\"#sa\" class=\"cmsmasters_button cmsmasters-icon-right-open\"><span>Vizualiza\u021bi Serviciul<\/span><\/a><\/div>\n<\/div><\/div>\n<div id=\"cmsmasters_column_zsutkm1hpa\" class=\"cmsmasters_column one_third\">\n<div class=\"cmsmasters_column_inner\"><div class=\"aligncenter\"><div class=\"cmsmasters_img  cmsmasters_image_c\"><img decoding=\"async\" src=\"https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/10\/avicenna-sac-ekimi-1.png\" alt=\"Sa\u00e7 Ekimi Banner - 1\" \/><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_21u0yvg363\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin cmsmasters_row_columns_behavior\">\n<div id=\"cmsmasters_column_qnnc72senn\" class=\"cmsmasters_column one_third\">\n<div class=\"cmsmasters_column_inner\"><div class=\"cmsmasters_text\">\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-27982 aligncenter\" src=\"https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/hastane-icon.png\" alt=\"Hastane\" width=\"75\" height=\"75\" srcset=\"https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/hastane-icon.png 75w, https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/hastane-icon-65x65.png 65w\" sizes=\"(max-width: 75px) 100vw, 75px\" \/><\/p>\n<h2 style=\"text-align: center;\">25 de ani de experien\u021b\u0103<\/h2>\n<p style=\"text-align: center;\">Asigurarea transplantului de p\u0103r \u00een spitale \u0219i s\u0103li de opera\u021bii sterile.<\/p>\n<\/div>\n<\/div><\/div>\n<div id=\"cmsmasters_column_kq25v9vbyq\" class=\"cmsmasters_column one_third\">\n<div class=\"cmsmasters_column_inner\"><div class=\"cmsmasters_text\">\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-27983 aligncenter\" src=\"https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/doktor-icon.png\" alt=\"Doktor icon\" width=\"75\" height=\"75\" srcset=\"https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/doktor-icon.png 75w, https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/doktor-icon-65x65.png 65w\" sizes=\"(max-width: 75px) 100vw, 75px\" \/><\/p>\n<h2 style=\"text-align: center;\">Echipa Profesional\u0103<\/h2>\n<p style=\"text-align: center;\">Chirurgi, medici \u0219i personal medical exper\u021bi \u0219i cu experien\u021b\u0103.<\/p>\n<\/div>\n<\/div><\/div>\n<div id=\"cmsmasters_column_rpo5h9lqn\" class=\"cmsmasters_column one_third\">\n<div class=\"cmsmasters_column_inner\"><div class=\"cmsmasters_text\">\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-27986\" src=\"https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/kalite-icon.png\" alt=\"Kalite icon\" width=\"54\" height=\"82\" \/><\/p>\n<h2 style=\"text-align: center;\">Calitatea Avicenna<\/h2>\n<p style=\"text-align: center;\">Toate tehnicile de transplant de p\u0103r sunt efectuate cu dispozitive de ultim\u0103 genera\u021bie.<\/p>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_9qbm0m47oq\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_fullwidth\">\n<div id=\"frm\" class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner cmsmasters_row_fullwidth\">\n<div class=\"cmsmasters_row_margin\">\n<div id=\"cmsmasters_column_utmcbh6ef\" class=\"cmsmasters_column two_third cmsmasters_column_sticky\">\n<div class=\"cmsmasters_column_inner\"><div class=\"cmsmasters_img  cmsmasters_image_l\"><a href=\"https:\/\/avicennaint.com\/wp-content\/uploads\/2022\/05\/avicenna-international-hospital-istanbul-maxq-34sn-imp.mp4\" rel=\"ilightbox[img_6a56da9c995ae]\"><img decoding=\"async\" src=\"https:\/\/avicennaint.com\/wp-content\/uploads\/2021\/11\/avicenna-international-hospital-video-cover-play.jpeg\" alt=\"Avicenna International Hospital Video Cover\" \/><\/a><\/div>\n<\/div><\/div>\n<div id=\"cmsmasters_column_cukx9rxp9o\" class=\"cmsmasters_column one_third\">\n<div class=\"cmsmasters_column_inner\"><div id=\"cmsmasters_fb_zu6m5mtvok\" class=\"cmsmasters_featured_block border-shadow\">\n<div class=\"featured_block_inner\">\n<div class=\"featured_block_text\">\n<p style=\"font-size: 18pt; color: #0c2442; text-align: center;\"><strong>Formular De Analiz\u0103 \u0218i Examinare Gratuit\u0103 A Transplantului De P\u0103r<\/strong><\/p>\n<div data-elementor-type=\"section\" data-elementor-id=\"88465\" class=\"elementor elementor-88465\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3499dafb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3499dafb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-7dccc590\" data-id=\"7dccc590\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1932955 elementor-mobile-button-align-stretch elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"1932955\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"frm\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" id=\"rofrm\" name=\"rofrm\" aria-label=\"rofrm\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"88465\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"1932955\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Grupul Spitalicesc Avicenna | Spitalul International Avicenna\" \/>\n\n\t\t\t\t\t\t\t<input type=\"hidden\" name=\"queried_id\" value=\"117294\"\/>\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-tel elementor-field-group elementor-column elementor-field-group-dropdown elementor-col-30 elementor-sm-30 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-dropdown\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tCodul \u021bar\u0103\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<input size=\"1\" type=\"tel\" name=\"form_fields[dropdown]\" id=\"form-field-dropdown\" class=\"elementor-field elementor-size-md  elementor-field-textual\" placeholder=\"+40\" required=\"required\" pattern=\"[0-9()#&amp;+*-=.]+\" title=\"Only numbers and phone characters (#, -, *, etc) are accepted.\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-tel elementor-field-group elementor-column elementor-field-group-phone elementor-col-70 elementor-sm-70 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-phone\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tNum\u0103r de telefon\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<input size=\"1\" type=\"tel\" name=\"form_fields[phone]\" id=\"form-field-phone\" class=\"elementor-field elementor-size-md  elementor-field-textual\" placeholder=\"7xxxxxxxxx\" required=\"required\" pattern=\"[0-9()#&amp;+*-=.]+\" title=\"Only numbers and phone characters (#, -, *, etc) are accepted.\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-md  elementor-field-textual\" placeholder=\"Prenume, Nume de familie\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-md  elementor-field-textual\" placeholder=\"E-mail\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-eleimpgclid elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[eleimpgclid]\" id=\"form-field-eleimpgclid\" class=\"elementor-field elementor-size-md  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-eleimputmterm elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[eleimputmterm]\" id=\"form-field-eleimputmterm\" class=\"elementor-field elementor-size-md  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-eleimpadgroupname elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[eleimpadgroupname]\" id=\"form-field-eleimpadgroupname\" class=\"elementor-field elementor-size-md  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-md\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Trimite<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54a5981f elementor-widget elementor-widget-html\" data-id=\"54a5981f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<input type=\"hidden\" id=\"ip_address\">\n<input type=\"hidden\" id=\"country_code\">\n<input type=\"hidden\" id=\"cc\">\n<script>\n\ndocument.addEventListener('DOMContentLoaded', function() { \ndocument.getElementById('form-field-phone').setAttribute('minlength',8);\ndocument.getElementById('form-field-phone').setAttribute('maxlength',12);\ndocument.getElementById('form-field-phone').setAttribute('pattern', '[0-9]+');\n});\n\ndocument.addEventListener('DOMContentLoaded', function() {\n  var phoneNumberField = document.getElementById('form-field-phone');\n  phoneNumberField.addEventListener('input', function() {\n      var currentValue = phoneNumberField.value;\n      if (currentValue.length === 1 && currentValue === '0') {\n          phoneNumberField.value = '';\n      }\n  });\n});\n\ndocument.addEventListener('DOMContentLoaded', function() {\n  var phoneNumberField = document.getElementById('form-field-phone');\n  document.querySelector('form.elementor-form').addEventListener('submit', function(event) {\n      event.preventDefault();\n      var phoneNumber = phoneNumberField.value;\n      phoneNumber = phoneNumber.replace(\/^0\/, '');\n      phoneNumberField.value = phoneNumber;\n  });\n});\n\n  \/\/ Replace 'your_access_token' with your actual access token from ipinfo.io\n  const accessToken = '90acc2371b701d';\n\n  \/\/ Make a request to ipinfo.io\n  fetch(`https:\/\/ipinfo.io?token=${accessToken}`)\n    .then(response => response.json())\n    .then(data => {\n      const ipAddress = data.ip;\n      const countryCode = data.country;\n\n      console.log('IP Address:', ipAddress);\n      console.log('Country Code:', countryCode);\n\n      document.getElementById(\"ip_address\").value = ipAddress;\n      document.getElementById(\"country_code\").value = countryCode;\n\n      \/\/ Update \"cc\" text based on the country code\n      const ccElement = document.getElementById(\"cc\");\n      switch (countryCode) {\n        case 'AF': ccElement.value = '+93'; break;\n        case 'AL': ccElement.value = '+355'; break;\n        case 'DZ': ccElement.value = '+213'; break;\n        case 'AS': ccElement.value = '+1684'; break;\n        case 'AD': ccElement.value = '+376'; break;\n        case 'AO': ccElement.value = '+244'; break;\n        case 'AI': ccElement.value = '+1264'; break;\n        case 'AQ': ccElement.value = '+672'; break;\n        case 'AG': ccElement.value = '+1268'; break;\n        case 'AR': ccElement.value = '+54'; break;\n        case 'AM': ccElement.value = '+374'; break;\n        case 'AW': ccElement.value = '+297'; break;\n        case 'AU': ccElement.value = '+61'; break;\n        case 'AT': ccElement.value = '+43'; break;\n        case 'AZ': ccElement.value = '+994'; break;\n        case 'BS': ccElement.value = '+1242'; break;\n        case 'BH': ccElement.value = '+973'; break;\n        case 'BD': ccElement.value = '+880'; break;\n        case 'BB': ccElement.value = '+1246'; break;\n        case 'BY': ccElement.value = '+375'; break;\n        case 'BE': ccElement.value = '+32'; break;\n        case 'BZ': ccElement.value = '+501'; break;\n        case 'BJ': ccElement.value = '+229'; break;\n        case 'BM': ccElement.value = '+1441'; break;\n        case 'BT': ccElement.value = '+975'; break;\n        case 'BO': ccElement.value = '+591'; break;\n        case 'BA': ccElement.value = '+387'; break;\n        case 'BW': ccElement.value = '+267'; break;\n        case 'BR': ccElement.value = '+55'; break;\n        case 'IO': ccElement.value = '+246'; break;\n        case 'VG': ccElement.value = '+1284'; break;\n        case 'BN': ccElement.value = '+673'; break;\n        case 'BG': ccElement.value = '+359'; break;\n        case 'BF': ccElement.value = '+226'; break;\n        case 'BI': ccElement.value = '+257'; break;\n        case 'KH': ccElement.value = '+855'; break;\n        case 'CM': ccElement.value = '+237'; break;\n        case 'CA': ccElement.value = '+1'; break;\n        case 'CV': ccElement.value = '+238'; break;\n        case 'KY': ccElement.value = '+1345'; break;\n        case 'CF': ccElement.value = '+236'; break;\n        case 'TD': ccElement.value = '+235'; break;\n        case 'CL': ccElement.value = '+56'; break;\n        case 'CN': ccElement.value = '+86'; break;\n        case 'CX': ccElement.value = '+61'; break;\n        case 'CC': ccElement.value = '+61'; break;\n        case 'CO': ccElement.value = '+57'; break;\n        case 'KM': ccElement.value = '+269'; break;\n        case 'CK': ccElement.value = '+682'; break;\n        case 'CR': ccElement.value = '+506'; break;\n        case 'HR': ccElement.value = '+385'; break;\n        case 'CU': ccElement.value = '+53'; break;\n        case 'CW': ccElement.value = '+599'; break;\n        case 'CY': ccElement.value = '+357'; break;\n        case 'CZ': ccElement.value = '+420'; break;\n        case 'CD': ccElement.value = '+243'; break;\n        case 'DK': ccElement.value = '+45'; break;\n        case 'DJ': ccElement.value = '+253'; break;\n        case 'DM': ccElement.value = '+1767'; break;\n        case 'DO': ccElement.value = '+1809'; break;\n        case 'TL': ccElement.value = '+670'; break;\n        case 'EC': ccElement.value = '+593'; break;\n        case 'EG': ccElement.value = '+20'; break;\n        case 'SV': ccElement.value = '+503'; break;\n        case 'GQ': ccElement.value = '+240'; break;\n        case 'ER': ccElement.value = '+291'; break;\n        case 'EE': ccElement.value = '+372'; break;\n        case 'ET': ccElement.value = '+251'; break;\n        case 'FK': ccElement.value = '+500'; break;\n        case 'FO': ccElement.value = '+298'; break;\n        case 'FJ': ccElement.value = '+679'; break;\n        case 'FI': ccElement.value = '+358'; break;\n        case 'FR': ccElement.value = '+33'; break;\n        case 'PF': ccElement.value = '+689'; break;\n        case 'GA': ccElement.value = '+241'; break;\n        case 'GM': ccElement.value = '+220'; break;\n        case 'GE': ccElement.value = '+995'; break;\n        case 'DE': ccElement.value = '+49'; break;\n        case 'GH': ccElement.value = '+233'; break;\n        case 'GI': ccElement.value = '+350'; break;\n        case 'GR': ccElement.value = '+30'; break;\n        case 'GL': ccElement.value = '+299'; break;\n        case 'GD': ccElement.value = '+1473'; break;\n        case 'GU': ccElement.value = '+1671'; break;\n        case 'GT': ccElement.value = '+502'; break;\n        case 'GG': ccElement.value = '+441481'; break;\n        case 'GN': ccElement.value = '+224'; break;\n        case 'GW': ccElement.value = '+245'; break;\n        case 'GY': ccElement.value = '+592'; break;\n        case 'HT': ccElement.value = '+509'; break;\n        case 'HN': ccElement.value = '+504'; break;\n        case 'HK': ccElement.value = '+852'; break;\n        case 'HU': ccElement.value = '+36'; break;\n        case 'IS': ccElement.value = '+354'; break;\n        case 'IN': ccElement.value = '+91'; break;\n        case 'ID': ccElement.value = '+62'; break;\n        case 'IR': ccElement.value = '+98'; break;\n        case 'IQ': ccElement.value = '+964'; break;\n        case 'IE': ccElement.value = '+353'; break;\n        case 'IM': ccElement.value = '+441624'; break;\n        case 'IL': ccElement.value = '+972'; break;\n        case 'IT': ccElement.value = '+39'; break;\n        case 'CI': ccElement.value = '+225'; break;\n        case 'JM': ccElement.value = '+1876'; break;\n        case 'JP': ccElement.value = '+81'; break;\n        case 'JE': ccElement.value = '+441534'; break;\n        case 'JO': ccElement.value = '+962'; break;\n        case 'KZ': ccElement.value = '+7'; break;\n        case 'KE': ccElement.value = '+254'; break;\n        case 'KI': ccElement.value = '+686'; break;\n        case 'XK': ccElement.value = '+383'; break;\n        case 'KW': ccElement.value = '+965'; break;\n        case 'KG': ccElement.value = '+996'; break;\n        case 'LA': ccElement.value = '+856'; break;\n        case 'LV': ccElement.value = '+371'; break;\n        case 'LB': ccElement.value = '+961'; break;\n        case 'LS': ccElement.value = '+266'; break;\n        case 'LR': ccElement.value = '+231'; break;\n        case 'LY': ccElement.value = '+218'; break;\n        case 'LI': ccElement.value = '+423'; break;\n        case 'LT': ccElement.value = '+370'; break;\n        case 'LU': ccElement.value = '+352'; break;\n        case 'MO': ccElement.value = '+853'; break;\n        case 'MK': ccElement.value = '+389'; break;\n        case 'MG': ccElement.value = '+261'; break;\n        case 'MW': ccElement.value = '+265'; break;\n        case 'MY': ccElement.value = '+60'; break;\n        case 'MV': ccElement.value = '+960'; break;\n        case 'ML': ccElement.value = '+223'; break;\n        case 'MT': ccElement.value = '+356'; break;\n        case 'MH': ccElement.value = '+692'; break;\n        case 'MR': ccElement.value = '+222'; break;\n        case 'MU': ccElement.value = '+230'; break;\n        case 'YT': ccElement.value = '+262'; break;\n        case 'MX': ccElement.value = '+52'; break;\n        case 'FM': ccElement.value = '+691'; break;\n        case 'MD': ccElement.value = '+373'; break;\n        case 'MC': ccElement.value = '+377'; break;\n        case 'MN': ccElement.value = '+976'; break;\n        case 'ME': ccElement.value = '+382'; break;\n        case 'MS': ccElement.value = '+1664'; break;\n        case 'MA': ccElement.value = '+212'; break;\n        case 'MZ': ccElement.value = '+258'; break;\n        case 'MM': ccElement.value = '+95'; break;\n        case 'NA': ccElement.value = '+264'; break;\n        case 'NR': ccElement.value = '+674'; break;\n        case 'NP': ccElement.value = '+977'; break;\n        case 'NL': ccElement.value = '+31'; break;\n        case 'AN': ccElement.value = '+599'; break;\n        case 'NC': ccElement.value = '+687'; break;\n        case 'NZ': ccElement.value = '+64'; break;\n        case 'NI': ccElement.value = '+505'; break;\n        case 'NE': ccElement.value = '+227'; break;\n        case 'NG': ccElement.value = '+234'; break;\n        case 'NU': ccElement.value = '+683'; break;\n        case 'KP': ccElement.value = '+850'; break;\n        case 'MP': ccElement.value = '+1670'; break;\n        case 'NO': ccElement.value = '+47'; break;\n        case 'OM': ccElement.value = '+968'; break;\n        case 'PK': ccElement.value = '+92'; break;\n        case 'PW': ccElement.value = '+680'; break;\n        case 'PS': ccElement.value = '+970'; break;\n        case 'PA': ccElement.value = '+507'; break;\n        case 'PG': ccElement.value = '+675'; break;\n        case 'PY': ccElement.value = '+595'; break;\n        case 'PE': ccElement.value = '+51'; break;\n        case 'PH': ccElement.value = '+63'; break;\n        case 'PN': ccElement.value = '+64'; break;\n        case 'PL': ccElement.value = '+48'; break;\n        case 'PT': ccElement.value = '+351'; break;\n        case 'PR': ccElement.value = '+1787'; break;\n        case 'QA': ccElement.value = '+974'; break;\n        case 'CG': ccElement.value = '+242'; break;\n        case 'RE': ccElement.value = '+262'; break;\n        case 'RO': ccElement.value = '+40'; break;\n        case 'RU': ccElement.value = '+7'; break;\n        case 'RW': ccElement.value = '+250'; break;\n        case 'BL': ccElement.value = '+590'; break;\n        case 'SH': ccElement.value = '+290'; break;\n        case 'KN': ccElement.value = '+1869'; break;\n        case 'LC': ccElement.value = '+1758'; break;\n        case 'MF': ccElement.value = '+590'; break;\n        case 'PM': ccElement.value = '+508'; break;\n        case 'VC': ccElement.value = '+1784'; break;\n        case 'WS': ccElement.value = '+685'; break;\n        case 'SM': ccElement.value = '+378'; break;\n        case 'ST': ccElement.value = '+239'; break;\n        case 'SA': ccElement.value = '+966'; break;\n        case 'SN': ccElement.value = '+221'; break;\n        case 'RS': ccElement.value = '+381'; break;\n        case 'SC': ccElement.value = '+248'; break;\n        case 'SL': ccElement.value = '+232'; break;\n        case 'SG': ccElement.value = '+65'; break;\n        case 'SX': ccElement.value = '+1721'; break;\n        case 'SK': ccElement.value = '+421'; break;\n        case 'SI': ccElement.value = '+386'; break;\n        case 'SB': ccElement.value = '+677'; break;\n        case 'SO': ccElement.value = '+252'; break;\n        case 'ZA': ccElement.value = '+27'; break;\n        case 'KR': ccElement.value = '+82'; break;\n        case 'SS': ccElement.value = '+211'; break;\n        case 'ES': ccElement.value = '+34'; break;\n        case 'LK': ccElement.value = '+94'; break;\n        case 'SD': ccElement.value = '+249'; break;\n        case 'SR': ccElement.value = '+597'; break;\n        case 'SJ': ccElement.value = '+47'; break;\n        case 'SZ': ccElement.value = '+268'; break;\n        case 'SE': ccElement.value = '+46'; break;\n        case 'CH': ccElement.value = '+41'; break;\n        case 'SY': ccElement.value = '+963'; break;\n        case 'TW': ccElement.value = '+886'; break;\n        case 'TJ': ccElement.value = '+992'; break;\n        case 'TZ': ccElement.value = '+255'; break;\n        case 'TH': ccElement.value = '+66'; break;\n        case 'TG': ccElement.value = '+228'; break;\n        case 'TK': ccElement.value = '+690'; break;\n        case 'TO': ccElement.value = '+676'; break;\n        case 'TT': ccElement.value = '+1868'; break;\n        case 'TN': ccElement.value = '+216'; break;\n        case 'TR': ccElement.value = '+90'; break;\n        case 'TM': ccElement.value = '+993'; break;\n        case 'TC': ccElement.value = '+1649'; break;\n        case 'TV': ccElement.value = '+688'; break;\n        case 'VI': ccElement.value = '+1340'; break;\n        case 'UG': ccElement.value = '+256'; break;\n        case 'UA': ccElement.value = '+380'; break;\n        case 'AE': ccElement.value = '+971'; break;\n        case 'GB': ccElement.value = '+44'; break;\n        case 'US': ccElement.value = '+1'; break;\n        case 'UY': ccElement.value = '+598'; break;\n        case 'UZ': ccElement.value = '+998'; break;\n        case 'VU': ccElement.value = '+678'; break;\n        case 'VA': ccElement.value = '+379'; break;\n        case 'VE': ccElement.value = '+58'; break;\n        case 'VN': ccElement.value = '+84'; break;\n        case 'WF': ccElement.value = '+681'; break;\n        case 'EH': ccElement.value = '+212'; break;\n        case 'YE': ccElement.value = '+967'; break;\n        case 'ZM': ccElement.value = '+260'; break;\n        case 'ZW': ccElement.value = '+263'; break;\n        \/\/ Add more cases for other country codes as needed\n        default:\n          \/\/ Default value if the country code is not matched\n          ccElement.value = '';\n      }\n              \/\/ Set the value of \"tstfield\" based on the value of \"cc\"\n              const tstfieldElement = document.getElementById(\"form-field-dropdown\");\n              tstfieldElement.value = ccElement.value;\n    })\n    .catch(error => {\n      console.error('Error fetching data:', error);\n    });\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_f6t7804oys\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div id=\"cmsmasters_column_rfnwxi9tj9\" class=\"cmsmasters_column one_half\">\n<div class=\"cmsmasters_column_inner\"><div class=\"aligncenter\"><div class=\"cmsmasters_img  cmsmasters_image_c\"><img decoding=\"async\" src=\"https:\/\/avicennaint.com\/wp-content\/uploads\/2021\/12\/cildiye-dr-ceyda-mumcuoglu-c-300x300.webp\" alt=\"Doktor Ceyda Mumcuo\u011flu\" \/><\/div><\/div><div id=\"cmsmasters_heading_fqadefksu\" class=\"cmsmasters_heading_wrap cmsmasters_heading_align_center\">\n\t<h3 class=\"cmsmasters_heading\">Dr. Ceyda Mumcuoglu<\/h3>\n<\/div>\n<\/div><\/div>\n<div id=\"cmsmasters_column_v8jiyly2ik\" class=\"cmsmasters_column one_half\">\n<div class=\"cmsmasters_column_inner\"><div class=\"aligncenter\"><div class=\"cmsmasters_img  cmsmasters_image_c\"><img decoding=\"async\" src=\"https:\/\/avicennaint.com\/wp-content\/uploads\/2021\/12\/sac-ekimi-pinar-zengin-c-300x300.webp\" alt=\"P\u0131nar Zengin\" \/><\/div><\/div><div id=\"cmsmasters_heading_op4khw4vts\" class=\"cmsmasters_heading_wrap cmsmasters_heading_align_center\">\n\t<h3 class=\"cmsmasters_heading\">Pinar Zengin<\/h3>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_moeqa7i6fo\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div id=\"sa\" class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div id=\"cmsmasters_column_ryox0qtw5\" class=\"cmsmasters_column one_third\">\n<div class=\"cmsmasters_column_inner\"><\/div><\/div>\n<div id=\"cmsmasters_column_lit8ujqnwj\" class=\"cmsmasters_column one_third\">\n<div class=\"cmsmasters_column_inner\"><div id=\"cmsmasters_icon_box_pssmhzxvwk\" class=\"cmsmasters_icon_box cmsmasters_icon_box_left box_icon_type_icon cmsmasters-icon-whatsapp\">\n<div class=\"icon_box_inner\">\n<h3 class=\"icon_box_heading\">WhatsApp<\/h3>\n<div class=\"icon_box_text\">\n<h3><a href=\"https:\/\/api.whatsapp.com\/send?phone=905426319423\"><strong>+90 542 631 94 23<\/strong><\/a><\/h3>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n<div id=\"cmsmasters_column_hhrz76ma1a\" class=\"cmsmasters_column one_third\">\n<div class=\"cmsmasters_column_inner\"><div id=\"cmsmasters_icon_box_e785qgjg7q\" class=\"cmsmasters_icon_box cmsmasters_icon_box_left box_icon_type_icon cmsmasters-icon-location\">\n<div class=\"icon_box_inner\">\n<h3 class=\"icon_box_heading\">Turcia Spitalul Adresa<\/h3>\n<div class=\"icon_box_text\">\n<h3><a href=\"https:\/\/g.page\/avicennainternationalhastanesi\" target=\"_blank\" rel=\"noopener\"><strong>Spitalul Avicenna International<\/strong><\/a><\/h3>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_qgwh685wf\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_fullwidth\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner cmsmasters_row_fullwidth\">\n<div class=\"cmsmasters_row_margin\">\n<div id=\"cmsmasters_column_2y0bckzk2a\" class=\"cmsmasters_column one_third\">\n<div class=\"cmsmasters_column_inner\"><div class=\"cmsmasters_video\">\n<div style=\"width: 300px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-29409-1\" width=\"300\" height=\"300\" loop autoplay preload=\"none\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/12\/sac-ekimi-3d-video.mp4?_=1\" \/><a href=\"https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/12\/sac-ekimi-3d-video.mp4\">https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/12\/sac-ekimi-3d-video.mp4<\/a><\/video><\/div><\/div>\n<\/div><\/div>\n<div id=\"cmsmasters_column_lin4t742oc\" class=\"cmsmasters_column two_third\">\n<div class=\"cmsmasters_column_inner\"><div id=\"cmsmasters_heading_m5v9lifsb2\" class=\"cmsmasters_heading_wrap cmsmasters_heading_align_left\">\n\t<h3 class=\"cmsmasters_heading\">TRANSPLANT DE P\u0102R<\/h3>\n<\/div><div class=\"cmsmasters_text\">\n<p style=\"text-align: left;\">C\u0103derea p\u0103rului are at\u00e2t cauze hormonale, genetice \u0219i legate de \u00eemb\u0103tr\u00e2nire.<br \/>\nAceast\u0103 afec\u021biune, care este mai frecvent\u0103 la b\u0103rba\u021bi dec\u00e2t la femei, este \u00een esen\u021b\u0103 un disconfort.<br \/>\nPoate crea o lips\u0103 de \u00eencredere \u00een sine \u0219i poate provoca probleme psihologice.<br \/>\nDezvoltarea tehnicilor de transplant de p\u0103r \u00een ultimii ani a \u00eenceput s\u0103 ofere rezultate satisf\u0103c\u0103toare \u0219i<br \/>\nofer\u0103 tuturor posibilitatea de a-\u0219i rec\u0103p\u0103ta aspectul natural.<\/p>\n<\/div>\n<div id=\"cmsmasters_button_0nuv928s1\" class=\"button_wrap\"><a href=\"#frm\" class=\"cmsmasters_button cmsmasters-icon-right-open\"><span>\u00centreba\u021bi Pre\u021bul<\/span><\/a><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_3ycb73ls49\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div id=\"cmsmasters_column_i9q37boneb\" class=\"cmsmasters_column one_third\">\n<div class=\"cmsmasters_column_inner\"><div class=\"cmsmasters_text\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-28012 aligncenter\" src=\"https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/tik-icon.png\" alt=\"Tik icon\" width=\"50\" height=\"50\" srcset=\"https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/tik-icon.png 75w, https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/tik-icon-65x65.png 65w\" sizes=\"(max-width: 50px) 100vw, 50px\" \/><\/p>\n<h3 style=\"text-align: center;\"><strong>Rezultate Durabile<\/strong><\/h3>\n<p style=\"text-align: center;\">Cu tehnicile speciale de transplant de p\u0103r al Centrului De Transplant De P\u0103r Al Spitalului Avicenna, p\u0103rul dvs. nou va fi al dvs. pentru totdeauna.<\/p>\n<\/div>\n<\/div><\/div>\n<div id=\"cmsmasters_column_m44lip3w9s\" class=\"cmsmasters_column one_third\">\n<div class=\"cmsmasters_column_inner\"><div class=\"cmsmasters_text\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-28012 aligncenter\" src=\"https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/tik-icon.png\" alt=\"Tik icon\" width=\"50\" height=\"50\" srcset=\"https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/tik-icon.png 75w, https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/tik-icon-65x65.png 65w\" sizes=\"(max-width: 50px) 100vw, 50px\" \/><\/p>\n<h3 style=\"text-align: center;\"><strong>ASPECT NATURAL<\/strong><\/h3>\n<p style=\"text-align: center;\">P\u0103rul transplantat asigur\u0103 faptul c\u0103 tot p\u0103rul de pe scalp obtine un aspect 100% natural.<\/p>\n<\/div>\n<\/div><\/div>\n<div id=\"cmsmasters_column_mays2j1zdd\" class=\"cmsmasters_column one_third\">\n<div class=\"cmsmasters_column_inner\"><div class=\"cmsmasters_text\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-28012 aligncenter\" src=\"https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/tik-icon.png\" alt=\"Tik icon\" width=\"50\" height=\"50\" srcset=\"https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/tik-icon.png 75w, https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/tik-icon-65x65.png 65w\" sizes=\"(max-width: 50px) 100vw, 50px\" \/><\/p>\n<h3 style=\"text-align: center;\"><strong>PRETURI ACCESIBILE<\/strong><\/h3>\n<p style=\"text-align: center;\">Cu politicile noastre de pre\u021buri accesibile, nu va trebui s\u0103 fii bogat pentru a avea un transplant de p\u0103r grefat maxim.<\/p>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_8ifjz1iflj\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_fullwidth\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner cmsmasters_row_fullwidth\">\n<div class=\"cmsmasters_row_margin\">\n<div id=\"cmsmasters_column_dixpsqjic1\" class=\"cmsmasters_column two_third\">\n<div class=\"cmsmasters_column_inner\"><div id=\"cmsmasters_heading_5p0ooehlxj\" class=\"cmsmasters_heading_wrap cmsmasters_heading_align_left\">\n\t<h3 class=\"cmsmasters_heading\">DE CE AVICENNA?<\/h3>\n<\/div><div class=\"cmsmasters_text\">\n<ul>\n<li><strong>100% Satisfac\u021bia Pacientului<\/strong><br \/>\nCentrul Avicenna de transplant de p\u0103r ofer\u0103 un certificat de garan\u021bie pe via\u021b\u0103 tuturor pacien\u021bilor care au transplant de p\u0103r.<\/li>\n<li><strong>Solu\u021bia Potrivit\u0103 Pentru Necesit\u0103\u021bi Diferite<\/strong><br \/>\nFacem transplant de p\u0103r cu un plan de tratament potrivit pentru persoane de toate v\u00e2rstele, f\u0103r\u0103 a separa b\u0103rba\u021bii \u0219i femeile.<\/li>\n<li><strong>O Abordare\u00a0Orientata Spre Pacient<\/strong><br \/>\nNe ocup\u0103m de toate necesitatile pacien\u021bilor no\u0219tri, \u00eencepand de la transfer, hotelul \u00een care vor fi caza\u021bi, serviciile de\u00a0mas\u0103, plecarea \u00eenapoi.<\/li>\n<\/ul>\n<\/div>\n<div id=\"cmsmasters_button_r0xs7kvprc\" class=\"button_wrap\"><a href=\"#frm\" class=\"cmsmasters_button cmsmasters-icon-right-open\"><span>Programare Gratuit\u0103!<\/span><\/a><\/div>\n<\/div><\/div>\n<div id=\"cmsmasters_column_3t8cw49mku\" class=\"cmsmasters_column one_third\">\n<div class=\"cmsmasters_column_inner\"><div class=\"aligncenter\"><div class=\"cmsmasters_img  cmsmasters_image_c\"><img decoding=\"async\" src=\"https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/10\/avicenna-sac-ekimi-9.png\" alt=\"Sa\u00e7 Ekimi Banner - 3\" \/><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_g26iaicm0n\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div id=\"cmsmasters_column_ilq2t03m7\" class=\"cmsmasters_column one_third\">\n<div class=\"cmsmasters_column_inner\"><div class=\"cmsmasters_text\">\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: center;\"><strong>RAPORTARE<\/strong><\/h3>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-28053 size-full\" src=\"https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/raporlama.jpg\" alt=\"Raporlama\" width=\"257\" height=\"143\" \/><\/p>\n<p style=\"text-align: center;\">Pacien\u021bilor no\u0219tri, care vin din str\u0103in\u0103tate, le oferim servicii de informa\u021bii \u00een limba lor matern\u0103, \u00een leg\u0103tur\u0103 cu c\u0103l\u0103toria \u00een Turcia, pa\u0219apoarte, transport urban, comunica\u021bii, opera\u021biuni consulare.<\/p>\n<\/div>\n<\/div><\/div>\n<div id=\"cmsmasters_column_ozq9ilhkvz\" class=\"cmsmasters_column one_third\">\n<div class=\"cmsmasters_column_inner\"><div class=\"cmsmasters_text\">\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: center;\"><strong>TRANSFER VIP<\/strong><\/h3>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-28054 size-full\" src=\"https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/transfer.jpg\" alt=\"VIP Transfer\" width=\"257\" height=\"143\" \/><\/p>\n<p style=\"text-align: center;\">Transferul pacientului de la aeroport, plasarea \u00een hotelul unde va sta \u0219i transportul \u00eentre spital \u0219i hotel se efectueaz\u0103 cu calitatea Spitalului Avicenna.<\/p>\n<\/div>\n<\/div><\/div>\n<div id=\"cmsmasters_column_c095ssf9y\" class=\"cmsmasters_column one_third\">\n<div class=\"cmsmasters_column_inner\"><div class=\"cmsmasters_text\">\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: center;\"><strong>CAZARE<\/strong><\/h3>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-28052 size-full\" src=\"https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/konaklama.jpg\" alt=\"Konaklama\" width=\"257\" height=\"143\" \/><\/p>\n<p style=\"text-align: center;\">Nu v\u0103 face\u021bi griji cu privire la cazare! Facem toate aranjamentele pentru dvs. Aranj\u0103m cazare cu mic dejun la hotel de lux, care se afla \u00een aproprierea spitalului.<\/p>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_648hp9esf\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div id=\"cmsmasters_column_pwl8acqk37\" class=\"cmsmasters_column one_third\">\n<div class=\"cmsmasters_column_inner\"><div id=\"cmsmasters_heading_fbicndzozb\" class=\"cmsmasters_heading_wrap cmsmasters_heading_align_center\">\n\t<h2 class=\"cmsmasters_heading\">COMENTARIILE CENTRULUI DE TRANSPLANT DE P\u0102R AVICENNA<\/h2>\n<\/div><div class=\"cmsmasters_quotes_slider_wrap\">\n<div id=\"cmsmasters_quotes_slider_27tn5n68\" class=\"cmsmasters_owl_slider owl-carousel cmsmasters_quotes cmsmasters_quotes_slider cmsmasters_quotes_slider_type_center\"\r\n\t\t\t\" data-auto-play=\"10000\" data-pagination=\"false\" data-navigation=\"true\" data-navigation-prev=\"<span class='cmsmasters_prev_arrow'><span><\/span><\/span>\" data-navigation-next=\"<span class='cmsmasters_next_arrow'><span><\/span><\/span>\"><div class=\"cmsmasters_quote\">\n<!-- Start Quote Slider Center Article -->\r\n<article class=\"cmsmasters_quote_inner\" id=\"cmsmasters_quote_6a56da9ca5772\">\r\n\t<figure class=\"cmsmasters_quote_image\"><img loading=\"lazy\" decoding=\"async\" width=\"65\" height=\"65\" src=\"https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/avicenna-logo-mini-quotes-65x65.png\" class=\"attachment-cmsmasters-small-thumb size-cmsmasters-small-thumb\" alt=\"\" srcset=\"https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/avicenna-logo-mini-quotes-65x65.png 65w, https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/avicenna-logo-mini-quotes.png 115w\" sizes=\"(max-width: 65px) 100vw, 65px\" \/><\/figure><div class=\"cmsmasters_quote_content\">\n<div class=\"cmsmasters_img  cmsmasters_image_l\"><img decoding=\"async\" src=\"https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/kesme-isareti.png\" \/><\/div>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #eff2f1\">\u0130. Y\u0131ld\u0131z<br \/>\nCa rezultat al cercet\u0103rilor mele pe internet, am g\u0103sit Centrul de Transplant de P\u0103r al Spitalului Avicenna. Din primul moment am fost \u00eent\u00e2mpinat de o echip\u0103 de profesioni\u0219ti. M-am simtit foarte confortabil at\u00e2t \u00een \u200b\u200btimpul transplantului de p\u0103r, c\u00e2t \u0219i dup\u0103 transplantul de p\u0103r.<\/span><\/p>\n<div class=\"cmsmasters_img  cmsmasters_image_r\"><img decoding=\"async\" src=\"https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/kesme-isareti-sag.png\" \/><\/div>\n<\/div><\/article>\r\n<!-- Finish Quote Slider Center Article -->\r\n\r\n<\/div>\n<div class=\"cmsmasters_quote\">\n<!-- Start Quote Slider Center Article -->\r\n<article class=\"cmsmasters_quote_inner\" id=\"cmsmasters_quote_6a56da9ca5ff7\">\r\n\t<figure class=\"cmsmasters_quote_image\"><img loading=\"lazy\" decoding=\"async\" width=\"65\" height=\"65\" src=\"https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/avicenna-logo-mini-quotes-65x65.png\" class=\"attachment-cmsmasters-small-thumb size-cmsmasters-small-thumb\" alt=\"\" srcset=\"https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/avicenna-logo-mini-quotes-65x65.png 65w, https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/avicenna-logo-mini-quotes.png 115w\" sizes=\"(max-width: 65px) 100vw, 65px\" \/><\/figure><div class=\"cmsmasters_quote_content\">\n<div class=\"cmsmasters_img  cmsmasters_image_l\"><img decoding=\"async\" src=\"https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/kesme-isareti.png\" \/><\/div>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #eff2f1\">H. Demir<br \/>\nAm contactat Centrul de Transplant de P\u0103r Avicenna \u0219i mi s-a efectuat transplant de p\u0103r nedureros. Nu am sim\u021bit nici o durere sau discomfort \u00een timpul opera\u021biei. Conform unui anumit plan \u0219i program, am trecut u\u015for at\u00e2t prin procesele de pre-procesare, c\u00e2t \u0219i de post-procesare. Mul\u021bumesc celor care au contribuit.<\/span><\/p>\n<div class=\"cmsmasters_img  cmsmasters_image_r\"><img decoding=\"async\" src=\"https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/kesme-isareti-sag.png\" \/><\/div>\n<\/div><\/article>\r\n<!-- Finish Quote Slider Center Article -->\r\n\r\n<\/div>\n<div class=\"cmsmasters_quote\">\n<!-- Start Quote Slider Center Article -->\r\n<article class=\"cmsmasters_quote_inner\" id=\"cmsmasters_quote_6a56da9ca6376\">\r\n\t<figure class=\"cmsmasters_quote_image\"><img loading=\"lazy\" decoding=\"async\" width=\"65\" height=\"65\" src=\"https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/avicenna-logo-mini-quotes-65x65.png\" class=\"attachment-cmsmasters-small-thumb size-cmsmasters-small-thumb\" alt=\"\" srcset=\"https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/avicenna-logo-mini-quotes-65x65.png 65w, https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/avicenna-logo-mini-quotes.png 115w\" sizes=\"(max-width: 65px) 100vw, 65px\" \/><\/figure><div class=\"cmsmasters_quote_content\">\n<div class=\"cmsmasters_img  cmsmasters_image_l\"><img decoding=\"async\" src=\"https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/kesme-isareti.png\" \/><\/div>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #eff2f1\">A. Akdelen<br \/>\nDe c\u00e2nd ne-am \u00eent\u00e2lnit cu echipa de transplant de p\u0103r Avicenna din Ata\u0219ehir, am trecut printr-o faz\u0103 de transplant de p\u0103r foarte pl\u0103cut\u0103 \u0219i distractiv\u0103. Este un centru de transplant de p\u0103r pe care vi-l pot recomanda, situat \u00een partea anatolian\u0103 a Istanbulului, \u00een Ata\u0219ehir. Prietenii mei care suferiti de c\u0103derea p\u0103rului, \u00eel pute\u021bi alege cu sufletul lini\u0219tit.<\/span><\/p>\n<div class=\"cmsmasters_img  cmsmasters_image_r\"><img decoding=\"async\" src=\"https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/kesme-isareti-sag.png\" \/><\/div>\n<\/div><\/article>\r\n<!-- Finish Quote Slider Center Article -->\r\n\r\n<\/div>\n<div class=\"cmsmasters_quote\">\n<!-- Start Quote Slider Center Article -->\r\n<article class=\"cmsmasters_quote_inner\" id=\"cmsmasters_quote_6a56da9ca66c1\">\r\n\t<figure class=\"cmsmasters_quote_image\"><img loading=\"lazy\" decoding=\"async\" width=\"65\" height=\"65\" src=\"https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/avicenna-logo-mini-quotes-65x65.png\" class=\"attachment-cmsmasters-small-thumb size-cmsmasters-small-thumb\" alt=\"\" srcset=\"https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/avicenna-logo-mini-quotes-65x65.png 65w, https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/avicenna-logo-mini-quotes.png 115w\" sizes=\"(max-width: 65px) 100vw, 65px\" \/><\/figure><div class=\"cmsmasters_quote_content\">\n<div class=\"cmsmasters_img  cmsmasters_image_l\"><img decoding=\"async\" src=\"https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/kesme-isareti.png\" \/><\/div>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #eff2f1\">B. \u00d6zt\u00fcrk<br \/>\nAm avut mare noroc s\u0103 \u00eent\u00e2lnesc o echip\u0103 de exper\u021bi care \u00ee\u0219i cunosc meseria. A avea un transplant de p\u0103r \u00eentr-un mediu de spital este cu mult mai bine. Mediul spitalului m-a f\u0103cut s\u0103 m\u0103 simt \u00een siguran\u021b\u0103 din primul moment p\u00e2n\u0103 \u00een ultimul. A\u0219 dori s\u0103 mul\u021bumesc Centrului de Transplantare a P\u0103rului al Spitalului Avicenna.<\/span><\/p>\n<div class=\"cmsmasters_img  cmsmasters_image_r\"><img decoding=\"async\" src=\"https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/kesme-isareti-sag.png\" \/><\/div>\n<\/div><\/article>\r\n<!-- Finish Quote Slider Center Article -->\r\n\r\n<\/div>\n<div class=\"cmsmasters_quote\">\n<!-- Start Quote Slider Center Article -->\r\n<article class=\"cmsmasters_quote_inner\" id=\"cmsmasters_quote_6a56da9ca6a3b\">\r\n\t<figure class=\"cmsmasters_quote_image\"><img loading=\"lazy\" decoding=\"async\" width=\"65\" height=\"65\" src=\"https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/avicenna-logo-mini-quotes-65x65.png\" class=\"attachment-cmsmasters-small-thumb size-cmsmasters-small-thumb\" alt=\"\" srcset=\"https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/avicenna-logo-mini-quotes-65x65.png 65w, https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/avicenna-logo-mini-quotes.png 115w\" sizes=\"(max-width: 65px) 100vw, 65px\" \/><\/figure><div class=\"cmsmasters_quote_content\">\n<div class=\"cmsmasters_img  cmsmasters_image_l\"><img decoding=\"async\" src=\"https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/kesme-isareti.png\" \/><\/div>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #eff2f1\">S. Koyuncuo\u011flu<br \/>\nAm simtit de multe ori calitatea spitalului Avicenna Ata\u0219ehir. C\u00e2nd c\u0103utam un centru de transplantare a p\u0103rului, am aflat c\u0103 spitalul meu, unde merg regulat, are un centru propriu de transplant de p\u0103r. Centrul de Transplantare a P\u0103rului Avicenna m-a ajutat s\u0103 obtin un p\u0103r dens \u0219i natural, exact a\u0219a cum \u00eemi doream.<br \/>\n<\/span><\/p>\n<div class=\"cmsmasters_img  cmsmasters_image_r\"><img decoding=\"async\" src=\"https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/kesme-isareti-sag.png\" \/><\/div>\n<\/div><\/article>\r\n<!-- Finish Quote Slider Center Article -->\r\n\r\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n<div id=\"cmsmasters_column_ei6uegfmnl\" class=\"cmsmasters_column two_third cmsmasters_column_sticky\">\n<div class=\"cmsmasters_column_inner\"><div id=\"cmsmasters_video_wrap_ol3si24p0f\" class=\"cmsmasters_video_wrap\">\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-29409-2\" width=\"640\" height=\"360\" poster=\"https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/youtube-video-c.jpg\" preload=\"none\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/avicenna-sac-ekimi-video.mp4?_=2\" \/><a href=\"https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/avicenna-sac-ekimi-video.mp4\">https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/avicenna-sac-ekimi-video.mp4<\/a><\/video><\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_irhpcfqtcs\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_fullwidth\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner cmsmasters_row_fullwidth\">\n<div class=\"cmsmasters_row_margin\">\n<div id=\"cmsmasters_column_onkyj2hcr\" class=\"cmsmasters_column one_fourth\">\n<div class=\"cmsmasters_column_inner\"><\/div><\/div>\n<div id=\"cmsmasters_column_a4sy304pap\" class=\"cmsmasters_column one_half\">\n<div class=\"cmsmasters_column_inner\"><div class=\"cmsmasters_text\">\n<p><b>25 de ani de experien\u021b\u0103<\/b><\/p>\n<p><b>\u00een estetic\u0103 \u0219i chirurgie medical\u0103.<\/b><\/p>\n<h3><\/h3>\n<\/div>\n<div id=\"cmsmasters_heading_khgvlycif\" class=\"cmsmasters_heading_wrap cmsmasters_heading_align_left\">\n\t<h3 class=\"cmsmasters_heading\">AVICENNA PENTRU S\u0102N\u0102TATE \u0218I ESTETIC\u0102;<\/h3>\n<\/div><div class=\"cmsmasters_text\">\n<p>Spitalul Avicenna a fost \u00eenfiin\u021bat in 1992, ca una dintre cele mai consacrate organiza\u021bii private de \u00eengrijire a s\u0103n\u0103t\u0103\u021bii din Turcia care continu\u0103 s\u0103 ofere servicii de s\u0103n\u0103tate in cele patru spitale din Istanbul.<\/p>\n<h3><\/h3>\n<h3>4 spitale<br \/>\nPeste 300 de angaja\u021bi<br \/>\n150B + num\u0103rul de pacien\u021bi<br \/>\n500B + num\u0103rul de tranzac\u021bii<\/h3>\n<\/div>\n<\/div><\/div>\n<div id=\"cmsmasters_column_fdvqbf3o8\" class=\"cmsmasters_column one_fourth\">\n<div class=\"cmsmasters_column_inner\"><div class=\"aligncenter\"><div class=\"cmsmasters_img  cmsmasters_image_c\"><img decoding=\"async\" src=\"https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/golden-brand-avicenna-2-1-180x300.png\" alt=\"Avicenna Hastanesi - Y\u0131l\u0131n Sa\u011fl\u0131k Markas\u0131 \u00d6d\u00fcl\u00fc\" \/><\/div><\/div><div id=\"cmsmasters_heading_7z0il6sdi9\" class=\"cmsmasters_heading_wrap cmsmasters_heading_align_center\">\n\t<h4 class=\"cmsmasters_heading\">Pute\u021bi ob\u021bine un interviu preliminar gratuit \u0219i programarea medicului.<\/h4>\n<\/div><div id=\"cmsmasters_button_bnjvt0khl9\" class=\"button_wrap\"><a href=\"#frm\" class=\"cmsmasters_button cmsmasters-icon-right-open\"><span>Programare gratuit\u0103!<\/span><\/a><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_wb894t08ox\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div id=\"az\" class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div id=\"cmsmasters_column_gri0iqyqnn\" class=\"cmsmasters_column one_first\">\n<div class=\"cmsmasters_column_inner\"><div id=\"cmsmasters_heading_tdnmhq0wpa\" class=\"cmsmasters_heading_wrap cmsmasters_heading_align_left\">\n\t<h2 class=\"cmsmasters_heading\">Tot ce trebuie s\u0103 \u0219ti\u021bi despre transplantul de p\u0103r de la A la Z<\/h2>\n<\/div><ul id=\"cmsmasters_icon_list_items_sruk04gfbb\" class=\"cmsmasters_icon_list_items cmsmasters_icon_list_type_block cmsmasters_icon_list_pos_left cmsmasters_color_type_border\"><li id=\"cmsmasters_icon_list_item_tamz7lh8fu\" class=\"cmsmasters_icon_list_item\">\n<div class=\"cmsmasters_icon_list_item_inner\">\n<div class=\"cmsmasters_icon_list_icon_wrap\">\n<span class=\"cmsmasters_icon_list_icon cmsmasters-icon-ok\"><\/span>\n<\/div>\n<div class=\"cmsmasters_icon_list_item_content\">\n<h4 class=\"cmsmasters_icon_list_item_title\">Centrul de Transplant de P\u0103r Avicenna<\/h4>\n<div class=\"cmsmasters_icon_list_item_text\">\n<p>Personalul specializat \u00een transplant de p\u0103r din cadrul personalului Spitalului Avicenna din Istanbul rezolva problemele legate de p\u0103r ale clien\u021bilor s\u0103i. Cu pre\u021buri accesibile de transplant de p\u0103r, spitalul nostru este al\u0103turi pacien\u021bii s\u0103i \u015fi dup\u0103 transplantul de p\u0103r. Exper\u021bii no\u0219tri \u00een rezultatele transplantului de p\u0103r continu\u0103 s\u0103 r\u0103spund\u0103 la toate \u00eentreb\u0103rile clien\u021bilor.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/li><li id=\"cmsmasters_icon_list_item_6mag1n512d\" class=\"cmsmasters_icon_list_item\">\n<div class=\"cmsmasters_icon_list_item_inner\">\n<div class=\"cmsmasters_icon_list_icon_wrap\">\n<span class=\"cmsmasters_icon_list_icon cmsmasters-icon-ok\"><\/span>\n<\/div>\n<div class=\"cmsmasters_icon_list_item_content\">\n<h4 class=\"cmsmasters_icon_list_item_title\">Transplant De P\u0103r Nedureros<\/h4>\n<div class=\"cmsmasters_icon_list_item_text\">\n<p>La fel ca toate celelalte opera\u021bii chirurgicale cunoscute, opera\u021bia de transplant de p\u0103r nedureroas\u0103 este o procedur\u0103 care trebuie efectuat\u0103 \u00een mediul s\u0103lii de opera\u021bie. Pre\u021burile transplantului de p\u0103r sunt, de asemenea, foarte accesibile \u00een Spitalul Avicenna din Istanbul. Se fac eforturi intense pentru a se asigura c\u0103 aceast\u0103 procedur\u0103 s\u0103 fie finalizat\u0103 \u00een cel mai confortabil mod \u0219i c\u0103 pacientul s\u0103 nu simt\u0103 nicio durere \u00een timpul opera\u021biei. Anestezia se face \u00een mod normal cu un ac \u0219i exist\u0103 o durere de ac. Un dispozitiv de anestezie numit comfort-in este utilizat pentru a reduce aceast\u0103 durere la zero. Cu acest dispozitiv, medicamentul pentru anestezie este injectat sub piele cu presiune f\u0103r\u0103 a utiliza un ac. \u0218i apoi urmeaz\u0103 un proces nedureros de la \u00eenceputul p\u00e2n\u0103 la sf\u00e2r\u0219itul opera\u021biei.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/li><li id=\"cmsmasters_icon_list_item_lujufw08yr\" class=\"cmsmasters_icon_list_item\">\n<div class=\"cmsmasters_icon_list_item_inner\">\n<div class=\"cmsmasters_icon_list_icon_wrap\">\n<span class=\"cmsmasters_icon_list_icon cmsmasters-icon-ok\"><\/span>\n<\/div>\n<div class=\"cmsmasters_icon_list_item_content\">\n<h4 class=\"cmsmasters_icon_list_item_title\">Transplant De P\u0103r Sapphire FUE<\/h4>\n<div class=\"cmsmasters_icon_list_item_text\">\n<p>Transplantul de p\u0103r Sapphire FUE nu este o opera\u021bie ca \u0219i alte metode de transplant de p\u0103r, iar riscul de durere, cicatrici, infec\u021bii \u0219i s\u00e2nger\u0103ri \u00een timpul \u0219i dup\u0103 opera\u021bie este minimizat. Tehnica realizat\u0103 cu un v\u00e2rf de safir ob\u021binut din piatra cristalin\u0103 a elementului de safir natural se nume\u0219te transplant de p\u0103r SAPPHIRE FUE. Tehnica Sapphire Fue este tehnica utilizat\u0103 pentru deschiderea canalelor de transplant de p\u0103r. Canalele sunt deschise cu v\u00e2rfuri de cristal \u0219i astfel, canalele sunt deschise f\u0103r\u0103 se a deteriora \u021besutul pielii. Faptul c\u0103 \u021besutul nu este deteriorat accelereaz\u0103 \u0219i procesul de vindecare. Se ob\u021bin rezultate adecvate ale transplantului de p\u0103r.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/li><li id=\"cmsmasters_icon_list_item_zzupuw0yt\" class=\"cmsmasters_icon_list_item\">\n<div class=\"cmsmasters_icon_list_item_inner\">\n<div class=\"cmsmasters_icon_list_icon_wrap\">\n<span class=\"cmsmasters_icon_list_icon cmsmasters-icon-ok\"><\/span>\n<\/div>\n<div class=\"cmsmasters_icon_list_item_content\">\n<h4 class=\"cmsmasters_icon_list_item_title\">Transplant De P\u0103r DHI <\/h4>\n<div class=\"cmsmasters_icon_list_item_text\">\n<p>Transplantul de p\u0103r DHI este o tehnic\u0103 de transplant de p\u0103r r\u0103sp\u00e2ndit\u0103 din 2014. Acest proces, cunoscut \u0219i sub denumirea de tehnica stiloului, consta \u00een transferul foliculilor luati din zona de ceaf\u0103 prin metoda FUE prin plasarea lor \u00een instrumente medicale speciale numite \u201eIMPLANTER\u201d, \u00een zona de transplantare. \u00cen metoda transplantului de p\u0103r DHI, canelarea \u0219i transplantul de p\u0103r sunt efectuate \u00een acela\u0219i timp, reduc\u00e2nd astfel timpul de a\u0219teptare externa al foliculilor prelua\u021bi din zona donatoare. Tehnica transplantului de p\u0103r DHI este o metod\u0103 care permite transplantul f\u0103r\u0103 t\u0103ierea p\u0103rului existent. Prin aceast\u0103 tehnic\u0103 este asigurat un proces de recuperare rapid \u00een urma transplantului de p\u0103r.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/li><li id=\"cmsmasters_icon_list_item_tndj7jy43\" class=\"cmsmasters_icon_list_item\">\n<div class=\"cmsmasters_icon_list_item_inner\">\n<div class=\"cmsmasters_icon_list_icon_wrap\">\n<span class=\"cmsmasters_icon_list_icon cmsmasters-icon-ok\"><\/span>\n<\/div>\n<div class=\"cmsmasters_icon_list_item_content\">\n<h4 class=\"cmsmasters_icon_list_item_title\">Transplant De P\u0103r Prin Sedare<\/h4>\n<div class=\"cmsmasters_icon_list_item_text\">\n<p>Transplantul de p\u0103r prin sedare este recomandat\u0103 pacien\u021bilor care consider\u0103 c\u0103 pot prezenta anxietate, fric\u0103 \u0219i durere \u00een timpul transplantului de p\u0103r. Sedarea este un tip de anestezie. Sedarea are efecte de calmare a durerii \u0219i relaxare. Aceast\u0103 metod\u0103, care este potrivit\u0103 pentru pacien\u021bii care au transplant de p\u0103r \u00eentr-un mediu de spital, fiind realizat\u0103 de un anestezist. \u00cen timpul \u0219i dup\u0103 transplantul de p\u0103r, apare o u\u0219oar\u0103 somnolen\u021b\u0103 la pacient. Con\u0219tiin\u021ba pacientului este clar\u0103 pe tot parcursul procedurii,doar apare o mic\u0103 senza\u021bie de pl\u0103cere \/ relaxare. Poate fi aplicat\u0103 \u00een toate metodele de transplant de p\u0103r, indiferent daca este DHI sau Safir FUE. Este metoda ideal\u0103 pentru cei care vor s\u0103 transplanteze p\u0103rul ca \u00eentr-un vis.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/li><li id=\"cmsmasters_icon_list_item_59tgkpdv9q\" class=\"cmsmasters_icon_list_item\">\n<div class=\"cmsmasters_icon_list_item_inner\">\n<div class=\"cmsmasters_icon_list_icon_wrap\">\n<span class=\"cmsmasters_icon_list_icon cmsmasters-icon-ok\"><\/span>\n<\/div>\n<div class=\"cmsmasters_icon_list_item_content\">\n<h4 class=\"cmsmasters_icon_list_item_title\">Transplant De P\u0103r F\u0103r\u0103 B\u0103rbierit<\/h4>\n<div class=\"cmsmasters_icon_list_item_text\">\n<p>Ast\u0103zi, cea mai preferat\u0103 opera\u021bie estetic\u0103 pentru b\u0103rba\u021bi este, f\u0103r\u0103 \u00eendoial\u0103, transplantul de p\u0103r. Stilul de p\u0103r este, de asemenea, o problem\u0103 foarte important\u0103 pentru fiecare b\u0103rbat. \u00cen trecut, b\u0103rbierirea p\u0103rului \u00eenainte de transplantul de p\u0103r a f\u0103cut ca mul\u021bi b\u0103rba\u021bi s\u0103 ezite s\u0103 fac\u0103 un transplant de p\u0103r. Odat\u0103 cu dezvoltarea tehnologiilor actuale, transplantul de p\u0103r f\u0103r\u0103 b\u0103rbierit a devenit posibil \u0219i aceast\u0103 metod\u0103 este aplicat\u0103 cu succes \u00een Centrul de Transplant de P\u0103r Avicenna.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/li><li id=\"cmsmasters_icon_list_item_8rmpnx877p\" class=\"cmsmasters_icon_list_item\">\n<div class=\"cmsmasters_icon_list_item_inner\">\n<div class=\"cmsmasters_icon_list_icon_wrap\">\n<span class=\"cmsmasters_icon_list_icon cmsmasters-icon-ok\"><\/span>\n<\/div>\n<div class=\"cmsmasters_icon_list_item_content\">\n<h4 class=\"cmsmasters_icon_list_item_title\">Transplant De P\u0103r Comfort FUE<\/h4>\n<div class=\"cmsmasters_icon_list_item_text\">\n<p>\u00cen metoda de transplant de p\u0103r Comfort FUE este utilizat un dispozitiv medical numit dermojet. Acest dispozitiv amor\u021be\u0219te scalpul pacientului f\u0103r\u0103 ace, oferind anestezie prin presiune. Atunci pacientul nu simte nici o durere pe tot parcursul opera\u021biei. Transplantul de p\u0103r cu anestezie nedureroas\u0103 poate fi utilizat \u0219i pentru metoda Comfort FUE.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/li><li id=\"cmsmasters_icon_list_item_6qhurixe2i\" class=\"cmsmasters_icon_list_item\">\n<div class=\"cmsmasters_icon_list_item_inner\">\n<div class=\"cmsmasters_icon_list_icon_wrap\">\n<span class=\"cmsmasters_icon_list_icon cmsmasters-icon-ok\"><\/span>\n<\/div>\n<div class=\"cmsmasters_icon_list_item_content\">\n<h4 class=\"cmsmasters_icon_list_item_title\">Transplant De Gene<\/h4>\n<div class=\"cmsmasters_icon_list_item_text\">\n<p>Transplantul de gene, care este \u00een cre\u0219tere \u00een \u00eentreaga lume, este aplicat cu succes \u00een Centrul de Transplant de P\u0103r Avicenna. Nu trebuie uitat faptul c\u0103 frumuse\u021bea genelor este foarte important\u0103 nu numai pentru aspect, ci \u0219i pentru s\u0103n\u0103tatea ochilor.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/li><li id=\"cmsmasters_icon_list_item_putyyv22jo\" class=\"cmsmasters_icon_list_item\">\n<div class=\"cmsmasters_icon_list_item_inner\">\n<div class=\"cmsmasters_icon_list_icon_wrap\">\n<span class=\"cmsmasters_icon_list_icon cmsmasters-icon-ok\"><\/span>\n<\/div>\n<div class=\"cmsmasters_icon_list_item_content\">\n<h4 class=\"cmsmasters_icon_list_item_title\">Transplant De Musta\u021b\u0103<\/h4>\n<div class=\"cmsmasters_icon_list_item_text\">\n<p>Cel mai important factor pentru b\u0103rba\u021bi de a-\u0219i crea propriul stil este, f\u0103r\u0103 \u00eendoial\u0103, musta\u021ba lor. Oricui nu ii cre\u0219te musta\u021ba sau nu se simte confortabil cu aspectul must\u0103\u021bii poate face un transplant de musta\u021b\u0103 de calitate la Centrul de Transplant de P\u0103r Avicenna.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/li><li id=\"cmsmasters_icon_list_item_2nx1iape7o\" class=\"cmsmasters_icon_list_item\">\n<div class=\"cmsmasters_icon_list_item_inner\">\n<div class=\"cmsmasters_icon_list_icon_wrap\">\n<span class=\"cmsmasters_icon_list_icon cmsmasters-icon-ok\"><\/span>\n<\/div>\n<div class=\"cmsmasters_icon_list_item_content\">\n<h4 class=\"cmsmasters_icon_list_item_title\">Transplant De Barb\u0103<\/h4>\n<div class=\"cmsmasters_icon_list_item_text\">\n<p>Barba, care a fost la mod\u0103 cu diferite modele \u00een fiecare perioad\u0103 a istoriei, este un element important pentru fiecare b\u0103rbat.Oricui nu ii cre\u0219te barba, nu este mul\u021bumit de forma barbei sau nu are barba pe o anumit\u0103 parte a fe\u021bei din cauza unui traumatism poate face un transplant de barb\u0103.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/li><li id=\"cmsmasters_icon_list_item_63p8h0hz6p\" class=\"cmsmasters_icon_list_item\">\n<div class=\"cmsmasters_icon_list_item_inner\">\n<div class=\"cmsmasters_icon_list_icon_wrap\">\n<span class=\"cmsmasters_icon_list_icon cmsmasters-icon-ok\"><\/span>\n<\/div>\n<div class=\"cmsmasters_icon_list_item_content\">\n<h4 class=\"cmsmasters_icon_list_item_title\">Transplant De Spr\u00e2ncene<\/h4>\n<div class=\"cmsmasters_icon_list_item_text\">\n<p>Extragerea regulata a spr\u00e2ncenelor de catre femei, provoac\u0103 un eveniment de \u00eencetare de cre\u015ftere \u00een timp. Deoarece spr\u00e2ncenele \u00ee\u0219i pierd volumul \u0219i grosimea din tinere\u021be, femeile prefer\u0103 transplantul de spr\u00e2ncene.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/li><li id=\"cmsmasters_icon_list_item_12zk4zwsa\" class=\"cmsmasters_icon_list_item\">\n<div class=\"cmsmasters_icon_list_item_inner\">\n<div class=\"cmsmasters_icon_list_icon_wrap\">\n<span class=\"cmsmasters_icon_list_icon cmsmasters-icon-ok\"><\/span>\n<\/div>\n<div class=\"cmsmasters_icon_list_item_content\">\n<h4 class=\"cmsmasters_icon_list_item_title\">Mezoterapia P\u0103rului<\/h4>\n<div class=\"cmsmasters_icon_list_item_text\">\n<p>Mezoterapia p\u0103rului, care este preferat\u0103 pentru c\u0103derea p\u0103rului sau sub\u021bierea p\u0103rului, este o aplica\u021bie care ofer\u0103 rezultate foarte rapide. Organiza\u021bia American\u0103 a S\u0103n\u0103t\u0103\u021bii a confirmat c\u0103 opre\u0219te c\u0103derea p\u0103rului \u0219i ajut\u0103 la \u00eent\u0103rirea p\u0103rului sub\u021bire.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/li><li id=\"cmsmasters_icon_list_item_2riktfnrnv\" class=\"cmsmasters_icon_list_item\">\n<div class=\"cmsmasters_icon_list_item_inner\">\n<div class=\"cmsmasters_icon_list_icon_wrap\">\n<span class=\"cmsmasters_icon_list_icon cmsmasters-icon-ok\"><\/span>\n<\/div>\n<div class=\"cmsmasters_icon_list_item_content\">\n<h4 class=\"cmsmasters_icon_list_item_title\">Rezultatele Transplantului De P\u0103r<\/h4>\n<div class=\"cmsmasters_icon_list_item_text\">\n<p>Tehnologiile de transplant de p\u0103r se modernizeaz\u0103 \u00een fiecare zi \u0219i, astfel, ratele de succes \u00een rezultatele transplantului de p\u0103r cresc.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/li><li id=\"cmsmasters_icon_list_item_7u1fi1hygw\" class=\"cmsmasters_icon_list_item\">\n<div class=\"cmsmasters_icon_list_item_inner\">\n<div class=\"cmsmasters_icon_list_icon_wrap\">\n<span class=\"cmsmasters_icon_list_icon cmsmasters-icon-ok\"><\/span>\n<\/div>\n<div class=\"cmsmasters_icon_list_item_content\">\n<h4 class=\"cmsmasters_icon_list_item_title\">Transplant De P\u0103r Cu Fibre<\/h4>\n<div class=\"cmsmasters_icon_list_item_text\">\n<p>Aceast\u0103 metod\u0103, cunoscut\u0103 \u0219i sub denumirea de transplant artificial de p\u0103r, este preferat\u0103 de pacien\u021bii cu p\u0103r insuficient in zona de ceaf\u0103 \u0219i corp. De\u0219i a fost considerat\u0103 ca o metod\u0103 promi\u021b\u0103toare \u00een primii ani, a devenit o metod\u0103 neutilizat\u0103 de-a lungul timpului datorit\u0103 infec\u021biei \u0219i inflama\u021biilor care apar dup\u0103 procedur\u0103.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/li><li id=\"cmsmasters_icon_list_item_khqqr6iqbj\" class=\"cmsmasters_icon_list_item\">\n<div class=\"cmsmasters_icon_list_item_inner\">\n<div class=\"cmsmasters_icon_list_icon_wrap\">\n<span class=\"cmsmasters_icon_list_icon cmsmasters-icon-ok\"><\/span>\n<\/div>\n<div class=\"cmsmasters_icon_list_item_content\">\n<h4 class=\"cmsmasters_icon_list_item_title\">Transplant De Par Cu Ghea\u021b\u0103<\/h4>\n<div class=\"cmsmasters_icon_list_item_text\">\n<p>Principala caracteristic\u0103 a transplantului de p\u0103r cu ghea\u021b\u0103 este c\u0103 foliculii de p\u0103r prelua\u021bi de la pacient sunt p\u0103stra\u021bi \u0219i proteja\u021bi \u00eentr-o solu\u021bie rece \u00eenainte de transplant. Puterea foliculilor de p\u0103r p\u0103stra\u021bi \u00een aceast\u0103 solu\u021bie rece cre\u0219te \u0219i via\u021ba lor este prelungit\u0103.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/li><li id=\"cmsmasters_icon_list_item_s4tltwl2uq\" class=\"cmsmasters_icon_list_item\">\n<div class=\"cmsmasters_icon_list_item_inner\">\n<div class=\"cmsmasters_icon_list_icon_wrap\">\n<span class=\"cmsmasters_icon_list_icon cmsmasters-icon-ok\"><\/span>\n<\/div>\n<div class=\"cmsmasters_icon_list_item_content\">\n<h4 class=\"cmsmasters_icon_list_item_title\">Transplant De P\u0103r FUT<\/h4>\n<div class=\"cmsmasters_icon_list_item_text\">\n<p>Transplantul de p\u0103r FUT este o tehnic\u0103 care a fost efectuat\u0103 foarte des o perioad\u0103, dar acum este \u00eenlocuit\u0103 cu tehnica de transplant de p\u0103r FUE. \u00cen aceast\u0103 tehnic\u0103, \u00een timp ce se iau grefe, pielea din jur este \u00eendep\u0103rtat\u0103 \u0219i prin incizie. Acest lucru provoac\u0103 s\u00e2nger\u0103ri excesive \u0219i cicatrici \u00een zona donatoare. 20 la sut\u0103 din foliculii de p\u0103r lua\u021bi \u00een tehnica FUT sunt irosi\u021bi.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/li><li id=\"cmsmasters_icon_list_item_6er0my0xmt\" class=\"cmsmasters_icon_list_item\">\n<div class=\"cmsmasters_icon_list_item_inner\">\n<div class=\"cmsmasters_icon_list_icon_wrap\">\n<span class=\"cmsmasters_icon_list_icon cmsmasters-icon-ok\"><\/span>\n<\/div>\n<div class=\"cmsmasters_icon_list_item_content\">\n<h4 class=\"cmsmasters_icon_list_item_title\">Zona Donatoare<\/h4>\n<div class=\"cmsmasters_icon_list_item_text\">\n<p>De\u0219i p\u0103rul corpului poate fi utilizat ca donator \u00een transplantul de p\u0103r, nu este preferat dec\u00e2t \u00een cazurile cand pacientul este obligat s\u0103 fac\u0103 acest lucru. Zona de la ceafa dintre cele dou\u0103 urechi este acceptat\u0103 ca zon\u0103 donatoare \u00een \u00eentreaga lume. Pentru c\u0103 zona de la ceafa este considerat\u0103 cea mai bun\u0103 zon\u0103 donatoare cu cele mai bune rezultate.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/li><li id=\"cmsmasters_icon_list_item_7b91dyfi31\" class=\"cmsmasters_icon_list_item\">\n<div class=\"cmsmasters_icon_list_item_inner\">\n<div class=\"cmsmasters_icon_list_icon_wrap\">\n<span class=\"cmsmasters_icon_list_icon cmsmasters-icon-ok\"><\/span>\n<\/div>\n<div class=\"cmsmasters_icon_list_item_content\">\n<h4 class=\"cmsmasters_icon_list_item_title\">Repara\u021bia \u00cencerc\u0103rilor E\u0219uate De Transplant De P\u0103r<\/h4>\n<div class=\"cmsmasters_icon_list_item_text\">\n<p>Pacien\u021bii care nu au un aspect natural, nu au o densitate suficient\u0103 a p\u0103rului, au imaginea unui cap de iarb\u0103, au un aspect ca de parchet, au cicatrici excesive \u0219i au transplant de p\u0103r frontal nenatural \u00eenseamn\u0103 c\u0103 au suferit un transplant de p\u0103r nereu\u0219it. \u00cen centrul nostru se efectueaz\u0103 repararea transplantului de p\u0103r pentru pacien\u021bii care nu suferit un transplant de p\u0103r nereu\u015fit.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/li><li id=\"cmsmasters_icon_list_item_8x8hi8vxij\" class=\"cmsmasters_icon_list_item\">\n<div class=\"cmsmasters_icon_list_item_inner\">\n<div class=\"cmsmasters_icon_list_icon_wrap\">\n<span class=\"cmsmasters_icon_list_icon cmsmasters-icon-ok\"><\/span>\n<\/div>\n<div class=\"cmsmasters_icon_list_item_content\">\n<h4 class=\"cmsmasters_icon_list_item_title\">Transplant De P\u0103r Corporal<\/h4>\n<div class=\"cmsmasters_icon_list_item_text\">\n<p>\u00cen cazurile \u00een care foliculii de p\u0103r din zona capului nu sunt suficiente pentru transplantul de p\u0103r, poate fi necesar transplantul de p\u0103r din p\u0103rul corpului. R\u0103d\u0103cinile p\u0103rului pot fi luate din toate zonele, cum ar fi barb\u0103, piept, bra\u021be, picioare \u0219i spate.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/li><li id=\"cmsmasters_icon_list_item_ok677d6lcl\" class=\"cmsmasters_icon_list_item\">\n<div class=\"cmsmasters_icon_list_item_inner\">\n<div class=\"cmsmasters_icon_list_icon_wrap\">\n<span class=\"cmsmasters_icon_list_icon cmsmasters-icon-ok\"><\/span>\n<\/div>\n<div class=\"cmsmasters_icon_list_item_content\">\n<h4 class=\"cmsmasters_icon_list_item_title\">Transplant De P\u0103r Choi Implanter<\/h4>\n<div class=\"cmsmasters_icon_list_item_text\">\n<p>\u00cen tehnica Choi Implanter, nu se formeaz\u0103 urme de incizie. Foliculii de p\u0103r sunt lua\u021bi prin metoda FUE. Spre deosebire de aceasta, se utilizeaz\u0103 metoda canalului. \u00cen acest caz, poate fi efectuat un transplant dens de p\u0103r at\u00e2t prin transplant c\u00e2t \u0219i prin deschiderea canalului.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/li><li id=\"cmsmasters_icon_list_item_st5row93hg\" class=\"cmsmasters_icon_list_item\">\n<div class=\"cmsmasters_icon_list_item_inner\">\n<div class=\"cmsmasters_icon_list_icon_wrap\">\n<span class=\"cmsmasters_icon_list_icon cmsmasters-icon-ok\"><\/span>\n<\/div>\n<div class=\"cmsmasters_icon_list_item_content\">\n<h4 class=\"cmsmasters_icon_list_item_title\">Transplant De P\u0103r Organic<\/h4>\n<div class=\"cmsmasters_icon_list_item_text\">\n<p>Transplantul organic de p\u0103r este aplicarea \u021besutului preluat de la pacient pe pielea chelie prin injec\u021bie cu celule stem. \u00cen acest fel, zona pacientului pe care urmeaz\u0103 s\u0103 fie transplantul devine mult mai preg\u0103tit\u0103 pentru transplant.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/li><li id=\"cmsmasters_icon_list_item_nor03ui35\" class=\"cmsmasters_icon_list_item\">\n<div class=\"cmsmasters_icon_list_item_inner\">\n<div class=\"cmsmasters_icon_list_icon_wrap\">\n<span class=\"cmsmasters_icon_list_icon cmsmasters-icon-ok\"><\/span>\n<\/div>\n<div class=\"cmsmasters_icon_list_item_content\">\n<h4 class=\"cmsmasters_icon_list_item_title\">Centru De Transplant De Par Avi\u0307cenna<\/h4>\n<div class=\"cmsmasters_icon_list_item_text\">\n<p class=\"p1\"><span class=\"s1\">Personalul spitalului Avicenna din Istanbul remediaza problemele parului clientilor sai. In pretul interventiei , personalul nostru va fi alaturi de dumneavoastra intreg procesul , inainte si dupa interventie, pentru un rezultat cat mai bun.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/li><li id=\"cmsmasters_icon_list_item_ldfiu5x62m\" class=\"cmsmasters_icon_list_item\">\n<div class=\"cmsmasters_icon_list_item_inner\">\n<div class=\"cmsmasters_icon_list_icon_wrap\">\n<span class=\"cmsmasters_icon_list_icon cmsmasters-icon-ok\"><\/span>\n<\/div>\n<div class=\"cmsmasters_icon_list_item_content\">\n<h4 class=\"cmsmasters_icon_list_item_title\">Transplant De P\u0103r Nedureros<\/h4>\n<div class=\"cmsmasters_icon_list_item_text\">\n<p class=\"p1\"><span class=\"s1\">Ca toate celelalte operatii chirurgicale cunoscute , operatia de transplant de par este o procedura care trebuie efectuata in mediul salii de operatie.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Preturile fiind destul de accesibile , se fac eforturi intense pentru a se asigura ca aceasta procedura este cea mai confortabila si pacientul nu simte nici o durere in timul operatiei.Anestezia este o procedura efectuata de ac in conditii normale si exista o durere mica de ac.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Pentru a reduce aceasta durere la 0 se foloseste un dispozitiv de anestezie numit confort-in. Cu acest dispozitiv medicamentul anestezic este injectat sub presiune fara a folosii un ac, si un proces nedureros este urmat de la inceput pana la sfarsit.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/li><li id=\"cmsmasters_icon_list_item_v7kaw784qq\" class=\"cmsmasters_icon_list_item\">\n<div class=\"cmsmasters_icon_list_item_inner\">\n<div class=\"cmsmasters_icon_list_icon_wrap\">\n<span class=\"cmsmasters_icon_list_icon cmsmasters-icon-ok\"><\/span>\n<\/div>\n<div class=\"cmsmasters_icon_list_item_content\">\n<h4 class=\"cmsmasters_icon_list_item_title\">Metoda Sapphire FUE<\/h4>\n<div class=\"cmsmasters_icon_list_item_text\">\n<p class=\"p1\"><span class=\"s1\"><b>METODA SAPPHIRE FUE<\/b> nu este o operatie ca si celelalte metode de transplant de par si minimizeaza riscul de aparitie a durerii, cicatrici , infectiei si sangerarilor in timpul si dupa operatie.Tehnica cu varful de safir obtinut din piatra de cristal a elementului safir gasit in mod natural se numeste SAPPHIRE FUE. Este o tehnica folosita pentru deschiderea canalelor de transplant de par .Canalele sunt deschide cu capete de cristal,fara a deteriora textura pielii. Fara a deteriora tesutul , grabeste procesul de vindecare.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/li><li id=\"cmsmasters_icon_list_item_de4kun6jaj\" class=\"cmsmasters_icon_list_item\">\n<div class=\"cmsmasters_icon_list_item_inner\">\n<div class=\"cmsmasters_icon_list_icon_wrap\">\n<span class=\"cmsmasters_icon_list_icon cmsmasters-icon-ok\"><\/span>\n<\/div>\n<div class=\"cmsmasters_icon_list_item_content\">\n<h4 class=\"cmsmasters_icon_list_item_title\">Metoda DHI<\/h4>\n<div class=\"cmsmasters_icon_list_item_text\">\n<p class=\"p1\"><span class=\"s1\"><b>METODA DHI<\/b> este o tehnica care s a raspandit inca din anul 2014. acest procedeu , cunoscut si sub denumirea de tehnica creion, este transferul radacinilor prelevate din regiunea cu ceafa prin metoda FUE si plasat in stilouri medicale speciale numite IMPLANTER si transplantat in zona de plantat. In metoda DHI canelarea si transplantul de par sunt efectuate in acelasi timp, astfel timpul de asteptare a radacinilor prelevate de la ceafa este redus la minimum.Tehnica DHI este o metoda care permite transplantarea fara a taia parul existent. Cu aceasta tehnica procesul de recuperare este mai rapid.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/li><li id=\"cmsmasters_icon_list_item_h55v8gy2d9\" class=\"cmsmasters_icon_list_item\">\n<div class=\"cmsmasters_icon_list_item_inner\">\n<div class=\"cmsmasters_icon_list_icon_wrap\">\n<span class=\"cmsmasters_icon_list_icon cmsmasters-icon-ok\"><\/span>\n<\/div>\n<div class=\"cmsmasters_icon_list_item_content\">\n<h4 class=\"cmsmasters_icon_list_item_title\">Metoda Sedare<\/h4>\n<div class=\"cmsmasters_icon_list_item_text\">\n<p class=\"p1\"><span class=\"s1\"><b>METODA SEDARE<\/b> este recomandat pacientilor care considera ca pot suferi de anxietate, frica si durere in timpul interventiei. Sedarea este un tip de anestezie avand un efect calmant si relaxant. Aceasta metoda este data de un anestezist intr un cadru spitalicesc. In timpul si dupa interventie pacientul dezvolta un somn usor . Constiinta pacientului fiind deschisa pe toata durata procedurii si exista o usoara senzatie de placere\/relaxare.Poate fi aplicat in toate metodele de transplant de par, indiferent de DHI sau SAPPHIRE FUE . Este metoda ideala pentru cei care vor sa transplanteze parul pe gustul viselor.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/li><li id=\"cmsmasters_icon_list_item_kfzsqwqz6o\" class=\"cmsmasters_icon_list_item\">\n<div class=\"cmsmasters_icon_list_item_inner\">\n<div class=\"cmsmasters_icon_list_icon_wrap\">\n<span class=\"cmsmasters_icon_list_icon cmsmasters-icon-ok\"><\/span>\n<\/div>\n<div class=\"cmsmasters_icon_list_item_content\">\n<h4 class=\"cmsmasters_icon_list_item_title\">Transplant De P\u0103r Neharit<\/h4>\n<div class=\"cmsmasters_icon_list_item_text\">\n<p class=\"p1\"><span class=\"s1\">Astazi operatia chirurgicala plastica cea mai preferata de barbati este fara indoiala Transplantul de par . Modelul de par , este de asemenea foarte importanta pentru fiecare barbat. Rasul parului inaintea interventiei a determinat multi barbati sa evite transplantul de par.Odata cu dezvoltarea tehnologiilor de astazi, transplantul de par netaiat a devenit posibil si aceasta metoda este aplicata cu succes in Avicenna centrul de transplant de par.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/li><li id=\"cmsmasters_icon_list_item_rv2hgph09\" class=\"cmsmasters_icon_list_item\">\n<div class=\"cmsmasters_icon_list_item_inner\">\n<div class=\"cmsmasters_icon_list_icon_wrap\">\n<span class=\"cmsmasters_icon_list_icon cmsmasters-icon-ok\"><\/span>\n<\/div>\n<div class=\"cmsmasters_icon_list_item_content\">\n<h4 class=\"cmsmasters_icon_list_item_title\">Etapele De Baz\u0103 Ale Transplantului De P\u0103r<\/h4>\n<div class=\"cmsmasters_icon_list_item_text\">\n<ul class=\"ul1\">\n<li class=\"li1\"><b><\/b><span class=\"s2\"><b>Colectarea grefelor de p\u0103r (foliculi)<br \/>\n<\/b><\/span><\/li>\n<\/ul>\n<p class=\"p2\"><span class=\"s2\">Dup\u0103 ce locul donator este preg\u0103tit pentru procedur\u0103, foliculii de p\u0103r sunt colecta\u021bi unul c\u00e2te unul cu motorul FUE. Este foarte important ca r\u0103d\u0103cinile s\u0103 nu fie deteriorate. Fiecare din aceste r\u0103d\u0103cini, numite grefe, con\u021bine aproximativ 2-3 fire de p\u0103r.<\/span><\/p>\n<ul class=\"ul1\">\n<li class=\"li1\"><b><\/b><span class=\"s2\"><b>Deschiderea canalelor<br \/>\n<\/b><\/span><\/li>\n<\/ul>\n<p class=\"p2\"><span class=\"s2\">Deoarece canalele sunt locul de implantare a grefelor colectate, deschiderea dimensiunii corecte \u0219i a ad\u00e2ncimii corecte \u00een func\u021bie de m\u0103rimea grefelor care urmeaz\u0103 a fi transplantate, afecteaz\u0103 rata cre\u0219terii p\u0103rului transplantat. Unghiul canalului trebuie reglat bine pentru a asigura un aspect natural.<\/span><\/p>\n<ul class=\"ul1\">\n<li class=\"li1\"><b><\/b><span class=\"s2\"><b>Implantarea grefelor \u00een canale deschise<br \/>\n<\/b><\/span><\/li>\n<\/ul>\n<p class=\"p2\"><span class=\"s2\">\u00cen ultima etap\u0103, grefele colectate sunt implantate una c\u00e2te una la unghiuri de 40-45 de grade, iar opera\u021bia de transplant de p\u0103r este finalizat\u0103.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/li><li id=\"cmsmasters_icon_list_item_gtniy8eyzq\" class=\"cmsmasters_icon_list_item\">\n<div class=\"cmsmasters_icon_list_item_inner\">\n<div class=\"cmsmasters_icon_list_icon_wrap\">\n<span class=\"cmsmasters_icon_list_icon cmsmasters-icon-ok\"><\/span>\n<\/div>\n<div class=\"cmsmasters_icon_list_item_content\">\n<h4 class=\"cmsmasters_icon_list_item_title\">Tehnici Utilizate \u00cen Transplantul De P\u0103r<\/h4>\n<div class=\"cmsmasters_icon_list_item_text\">\n<p class=\"p1\"><span class=\"s1\">Etapele de baz\u0103 sunt acelea\u0219i \u00een toate tehnicile de transplant de p\u0103r. R\u0103d\u0103cinile sunt extrase, canalele sunt deschise \u0219i r\u0103d\u0103cinile sunt implantate \u00een aceste canale. Atributele care diferen\u021biaz\u0103 metodele de transplant de p\u0103r sunt cauzate de dispozitivul folosit la r\u0103d\u0103cina r\u0103d\u0103cinilor, de instrumentele medicale utilizate \u00een timpul deschiderii canalelor \u0219i \u00een timpul transplantului \u0219i aceste diferen\u021be duc la denumirea diferit\u0103 a tehnicilor de transplant de p\u0103r.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/li><li id=\"cmsmasters_icon_list_item_p92u552de\" class=\"cmsmasters_icon_list_item\">\n<div class=\"cmsmasters_icon_list_item_inner\">\n<div class=\"cmsmasters_icon_list_icon_wrap\">\n<span class=\"cmsmasters_icon_list_icon cmsmasters-icon-ok\"><\/span>\n<\/div>\n<div class=\"cmsmasters_icon_list_item_content\">\n<h4 class=\"cmsmasters_icon_list_item_title\">Ce Trebuie \u0218tiut Despre Transplantul De Par Si Procesul Postoperatoriu<\/h4>\n<div class=\"cmsmasters_icon_list_item_text\">\n<p class=\"p1\"><span class=\"s1\">C\u00e2t dureaz\u0103 o opera\u021bie de transplant de p\u0103r, este confortabil\u0103? <\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Opera\u021bia dureaz\u0103 aproximativ 6-7 ore. \u00cen timpul opera\u021biei nu se aplic\u0103 pacientului nostru anestezie general\u0103, nu se administreaz\u0103 narcoz\u0103. Opera\u021bia de transplant de p\u0103r se efectueaz\u0103 purt\u00e2nd un dialog cu pacientul nostru aflat sub anestezie local\u0103 sau sedare.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/li><li id=\"cmsmasters_icon_list_item_34rsn34oo\" class=\"cmsmasters_icon_list_item\">\n<div class=\"cmsmasters_icon_list_item_inner\">\n<div class=\"cmsmasters_icon_list_icon_wrap\">\n<span class=\"cmsmasters_icon_list_icon cmsmasters-icon-ok\"><\/span>\n<\/div>\n<div class=\"cmsmasters_icon_list_item_content\">\n<h4 class=\"cmsmasters_icon_list_item_title\">C\u00e2t timp trebuie s\u0103 aloc opera\u021biei de transplant de p\u0103r?<\/h4>\n<div class=\"cmsmasters_icon_list_item_text\">\n<p class=\"p1\"><span class=\"s1\">Av\u00e2nd \u00een vedere procedura pre \u015fi post operatorie opera\u021biei transplantului de p\u0103r, este suficient ca pacien\u021bii no\u0219tri s\u0103 aloce 3 zile. \u00cen aceast\u0103 perioad\u0103 de 3 zile lucrurile se desf\u0103\u0219oar\u0103 astfel:<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">\u00a0<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\"><b>Ziua 1 ( Implant ) :\u00a0<\/b> Ziua 1): procedura de transpunere a p\u0103r\u021bilor \u0219i tratament cu prp sunt finalizate \u00een spitalul nostru.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">\u00a0<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\"><b>Peste 2 zile ( Control ) :<\/b> Pacientul nostru este reg\u0103zduit \u00een spitalul nostru \u0219i se verific\u0103 dac\u0103 exist\u0103 vreo deteriorare, s\u00e2ngerare, infec\u021bie la grefele transplantate (r\u0103d\u0103cinile).<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">\u00a0<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\"><b>Peste 3 zile ( Prima sp\u0103lare ) :<\/b>\u00a0 Pacientul nostru este reinvitat la spital pentru primul proces de sp\u0103lare. O lo\u021biune special\u0103 se aplic\u0103 pe zonele \u00een care p\u0103rul este implantat \u0219i\u00a0 se a\u0219teapt\u0103 20 de minute, dup\u0103 care se efectueaz\u0103 o \u00eengrijire profesional\u0103.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\"><b>Peste 10 zile :<\/b>\u00a0 Transplantul de p\u0103r + Control + Sp\u0103larea p\u0103rului la sf\u00e2r\u0219itul perioadei de 13 zile. La sf\u00e2r\u0219itul acestei perioade, p\u0103rului pacientului nostru arata ca \u015fi p\u0103rul t\u0103iat scurt, \u00een timp ce ro\u0219ea\u021ba se reduce \u00een mare m\u0103sur\u0103. Rezultatele complete \u00een transplantul de p\u0103r\u00a0 apar \u00een timp de 6 -18 luni<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/li><li id=\"cmsmasters_icon_list_item_10pvmg8dco\" class=\"cmsmasters_icon_list_item\">\n<div class=\"cmsmasters_icon_list_item_inner\">\n<div class=\"cmsmasters_icon_list_icon_wrap\">\n<span class=\"cmsmasters_icon_list_icon cmsmasters-icon-ok\"><\/span>\n<\/div>\n<div class=\"cmsmasters_icon_list_item_content\">\n<h4 class=\"cmsmasters_icon_list_item_title\">Ce Este Transplantul De P\u0103r?<\/h4>\n<div class=\"cmsmasters_icon_list_item_text\">\n<p class=\"p1\"><span class=\"s1\">Transplantul de p\u0103r este o solu\u021bie natural\u0103 \u0219i permanent\u0103 a problemei de r\u0103rire a p\u0103rului \u0219i chelie cauzat\u0103 de c\u0103derea p\u0103rului. \u00cen transplantul de p\u0103r, foliculii de p\u0103r rezisten\u021bi genetic sunt colecta\u021bi de la ceafa pacientului \u0219i planta\u021bi \u00een canalele deschise \u00een zonele \u00een care s-a produs chelie sau r\u0103rirea p\u0103rului. Transplantul de p\u0103r este o micro-chirurgie efectuat\u0103 sub anestezie local\u0103. Prin urmare, trebuie efectuat \u00een mediul spitalicesc \u0219i \u00een prezen\u021ba unui anestezist.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/li><li id=\"cmsmasters_icon_list_item_2xawg2si3\" class=\"cmsmasters_icon_list_item\">\n<div class=\"cmsmasters_icon_list_item_inner\">\n<div class=\"cmsmasters_icon_list_icon_wrap\">\n<span class=\"cmsmasters_icon_list_icon cmsmasters-icon-ok\"><\/span>\n<\/div>\n<div class=\"cmsmasters_icon_list_item_content\">\n<h4 class=\"cmsmasters_icon_list_item_title\">Transplant de p\u0103r Comfort FUE<\/h4>\n<div class=\"cmsmasters_icon_list_item_text\">\n<p class=\"p1\"><span class=\"s1\">Un dispozitiv medical numit dermojet este utilizat \u00een transplantul de p\u0103r Comfort FUE. Acest dispozitiv anesteziaz\u0103 cu presiune \u0219i amorteste scalpul pacientului f\u0103r\u0103 ac. Apoi, pacientul nu simte nicio durere \u00een timpul opera\u021biei. De asemenea, pute\u021bi \u00eencerca transplantul de p\u0103r cu anestezie nedureroas\u0103 pentru metoda Comfort FUE.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/li><\/ul>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_9r6s76bdfm\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_fullwidth\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner cmsmasters_row_fullwidth\">\n<div class=\"cmsmasters_row_margin\">\n<div id=\"cmsmasters_column_srue0kpubs\" class=\"cmsmasters_column two_third\">\n<div class=\"cmsmasters_column_inner\"><div id=\"cmsmasters_heading_1m60kagpfx\" class=\"cmsmasters_heading_wrap cmsmasters_heading_align_center\">\n\t<h3 class=\"cmsmasters_heading\">Aveti ceva<\/h3>\n<\/div><div id=\"cmsmasters_heading_2xdt8n0i\" class=\"cmsmasters_heading_wrap cmsmasters_heading_align_center\">\n\t<h3 class=\"cmsmasters_heading\">\u00eentreb\u0103ri?<\/h3>\n<\/div><div id=\"cmsmasters_heading_uhs8w5dnp8\" class=\"cmsmasters_heading_wrap cmsmasters_heading_align_center\">\n\t<h3 class=\"cmsmasters_heading\">Nu ezita\u021bi s\u0103 ne contacta\u021bi!<\/h3>\n<\/div><div id=\"cmsmasters_heading_8ssmat8ulk\" class=\"cmsmasters_heading_wrap cmsmasters_heading_align_center\">\n\t<h3 class=\"cmsmasters_heading\">Suntem bucuro\u0219i s\u0103 v\u0103 acord\u0103m ajutor \u00een tot ceea ce este legat de transplantul de p\u0103r.<\/h3>\n<\/div><div id=\"cmsmasters_button_qnpr219z6o\" class=\"button_wrap\"><a href=\"#frm\" class=\"cmsmasters_button cmsmasters-icon-right-open\"><span>Contacta\u021bi-ne.<\/span><\/a><\/div>\n<\/div><\/div>\n<div id=\"cmsmasters_column_8hv6rqqve\" class=\"cmsmasters_column one_third\">\n<div class=\"cmsmasters_column_inner\"><div class=\"aligncenter\"><div class=\"cmsmasters_img  cmsmasters_image_c\"><img decoding=\"async\" src=\"https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/10\/avicenna-sac-ekimi-4.png\" alt=\"Sa\u00e7 Ekimi Banner - 5\" \/><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_yqvxm2tuth\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div id=\"cmsmasters_column_in55uany5k\" class=\"cmsmasters_column one_first\">\n<div class=\"cmsmasters_column_inner\"><p><\/p>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-29409","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Centrul De Transplant De P\u0103r Al Spitalului Avicenna<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/avicennaint.com\/ro\/transplant-de-par\/\" \/>\n<meta property=\"og:locale\" content=\"ro_RO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Centrul De Transplant De P\u0103r Al Spitalului Avicenna\" \/>\n<meta property=\"og:url\" content=\"https:\/\/avicennaint.com\/ro\/transplant-de-par\/\" \/>\n<meta property=\"og:site_name\" content=\"Spitalul International Avicenna\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/avicennaint\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-26T15:21:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/hastane-icon.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@avicennaintcom\" \/>\n<meta name=\"twitter:label1\" content=\"Timp estimat pentru citire\" \/>\n\t<meta name=\"twitter:data1\" content=\"20 de minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/avicennaint.com\\\/ro\\\/transplant-de-par\\\/\",\"url\":\"https:\\\/\\\/avicennaint.com\\\/ro\\\/transplant-de-par\\\/\",\"name\":\"Centrul De Transplant De P\u0103r Al Spitalului Avicenna\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/avicennaint.com\\\/ro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/avicennaint.com\\\/ro\\\/transplant-de-par\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/avicennaint.com\\\/ro\\\/transplant-de-par\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/avicennaint.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/hastane-icon.png\",\"datePublished\":\"2020-10-27T11:00:31+00:00\",\"dateModified\":\"2023-07-26T15:21:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/avicennaint.com\\\/ro\\\/transplant-de-par\\\/#breadcrumb\"},\"inLanguage\":\"ro-RO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/avicennaint.com\\\/ro\\\/transplant-de-par\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\\\/\\\/avicennaint.com\\\/ro\\\/transplant-de-par\\\/#primaryimage\",\"url\":\"https:\\\/\\\/avicennaint.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/hastane-icon.png\",\"contentUrl\":\"https:\\\/\\\/avicennaint.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/hastane-icon.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/avicennaint.com\\\/ro\\\/transplant-de-par\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/avicennaint.com\\\/ro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Centrul De Transplant De P\u0103r Al Spitalului Avicenna\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/avicennaint.com\\\/ro\\\/#website\",\"url\":\"https:\\\/\\\/avicennaint.com\\\/ro\\\/\",\"name\":\"Avicenna Hastanesi\",\"description\":\"Avicenna Atasehir International Hospital\",\"publisher\":{\"@id\":\"https:\\\/\\\/avicennaint.com\\\/ro\\\/#organization\"},\"alternateName\":\"Avicenna\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/avicennaint.com\\\/ro\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ro-RO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/avicennaint.com\\\/ro\\\/#organization\",\"name\":\"Avicenna Hastanesi\",\"alternateName\":\"Avicenna Hospital\",\"url\":\"https:\\\/\\\/avicennaint.com\\\/ro\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\\\/\\\/avicennaint.com\\\/ro\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/avicennaint.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/avicenna-logo-kare-blog.jpg\",\"contentUrl\":\"https:\\\/\\\/avicennaint.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/avicenna-logo-kare-blog.jpg\",\"width\":800,\"height\":450,\"caption\":\"Avicenna Hastanesi\"},\"image\":{\"@id\":\"https:\\\/\\\/avicennaint.com\\\/ro\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/avicennaint\",\"https:\\\/\\\/x.com\\\/avicennaintcom\",\"https:\\\/\\\/mastodon.social\\\/@avicenna\",\"https:\\\/\\\/www.instagram.com\\\/avicennahastanesi\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/avicennahastanesi\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@avicennaint\\\/\",\"https:\\\/\\\/www.instagram.com\\\/avicennaint\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Centrul De Transplant De P\u0103r Al Spitalului Avicenna","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/avicennaint.com\/ro\/transplant-de-par\/","og_locale":"ro_RO","og_type":"article","og_title":"Centrul De Transplant De P\u0103r Al Spitalului Avicenna","og_url":"https:\/\/avicennaint.com\/ro\/transplant-de-par\/","og_site_name":"Spitalul International Avicenna","article_publisher":"https:\/\/www.facebook.com\/avicennaint","article_modified_time":"2023-07-26T15:21:52+00:00","og_image":[{"url":"https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/hastane-icon.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@avicennaintcom","twitter_misc":{"Timp estimat pentru citire":"20 de minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/avicennaint.com\/ro\/transplant-de-par\/","url":"https:\/\/avicennaint.com\/ro\/transplant-de-par\/","name":"Centrul De Transplant De P\u0103r Al Spitalului Avicenna","isPartOf":{"@id":"https:\/\/avicennaint.com\/ro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/avicennaint.com\/ro\/transplant-de-par\/#primaryimage"},"image":{"@id":"https:\/\/avicennaint.com\/ro\/transplant-de-par\/#primaryimage"},"thumbnailUrl":"https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/hastane-icon.png","datePublished":"2020-10-27T11:00:31+00:00","dateModified":"2023-07-26T15:21:52+00:00","breadcrumb":{"@id":"https:\/\/avicennaint.com\/ro\/transplant-de-par\/#breadcrumb"},"inLanguage":"ro-RO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/avicennaint.com\/ro\/transplant-de-par\/"]}]},{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/avicennaint.com\/ro\/transplant-de-par\/#primaryimage","url":"https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/hastane-icon.png","contentUrl":"https:\/\/avicennaint.com\/wp-content\/uploads\/2020\/09\/hastane-icon.png"},{"@type":"BreadcrumbList","@id":"https:\/\/avicennaint.com\/ro\/transplant-de-par\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/avicennaint.com\/ro\/"},{"@type":"ListItem","position":2,"name":"Centrul De Transplant De P\u0103r Al Spitalului Avicenna"}]},{"@type":"WebSite","@id":"https:\/\/avicennaint.com\/ro\/#website","url":"https:\/\/avicennaint.com\/ro\/","name":"Avicenna Hastanesi","description":"Avicenna Atasehir International Hospital","publisher":{"@id":"https:\/\/avicennaint.com\/ro\/#organization"},"alternateName":"Avicenna","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/avicennaint.com\/ro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ro-RO"},{"@type":"Organization","@id":"https:\/\/avicennaint.com\/ro\/#organization","name":"Avicenna Hastanesi","alternateName":"Avicenna Hospital","url":"https:\/\/avicennaint.com\/ro\/","logo":{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/avicennaint.com\/ro\/#\/schema\/logo\/image\/","url":"https:\/\/avicennaint.com\/wp-content\/uploads\/2021\/04\/avicenna-logo-kare-blog.jpg","contentUrl":"https:\/\/avicennaint.com\/wp-content\/uploads\/2021\/04\/avicenna-logo-kare-blog.jpg","width":800,"height":450,"caption":"Avicenna Hastanesi"},"image":{"@id":"https:\/\/avicennaint.com\/ro\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/avicennaint","https:\/\/x.com\/avicennaintcom","https:\/\/mastodon.social\/@avicenna","https:\/\/www.instagram.com\/avicennahastanesi\/","https:\/\/www.linkedin.com\/company\/avicennahastanesi\/","https:\/\/www.youtube.com\/@avicennaint\/","https:\/\/www.instagram.com\/avicennaint\/"]}]}},"_links":{"self":[{"href":"https:\/\/avicennaint.com\/ro\/wp-json\/wp\/v2\/pages\/29409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/avicennaint.com\/ro\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/avicennaint.com\/ro\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/avicennaint.com\/ro\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/avicennaint.com\/ro\/wp-json\/wp\/v2\/comments?post=29409"}],"version-history":[{"count":0,"href":"https:\/\/avicennaint.com\/ro\/wp-json\/wp\/v2\/pages\/29409\/revisions"}],"wp:attachment":[{"href":"https:\/\/avicennaint.com\/ro\/wp-json\/wp\/v2\/media?parent=29409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}